{"id":380548,"date":"2024-06-11T00:01:00","date_gmt":"2024-06-10T22:01:00","guid":{"rendered":"https:\/\/medizinonline.com\/?p=380548"},"modified":"2024-07-26T10:26:40","modified_gmt":"2024-07-26T08:26:40","slug":"psicologia-clinica-no-contexto-das-doencas-cardiovasculares","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/pt-pt\/psicologia-clinica-no-contexto-das-doencas-cardiovasculares\/","title":{"rendered":"Psicologia cl\u00ednica no contexto das doen\u00e7as cardiovasculares"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>As perturba\u00e7\u00f5es mentais ocorrem frequentemente no contexto de doen\u00e7as cardiovasculares e podem ter um impacto negativo no progn\u00f3stico som\u00e1tico. Regra geral, no entanto, existem abordagens eficazes para tratar estas queixas. Dever\u00e3o ser tidas em conta recomenda\u00e7\u00f5es espec\u00edficas.<\/strong><\/p>\n\n<!--more-->\n\n<p class=\"wp-block-paragraph\">O Sr. M. tem 63 anos e foi tratado de um enfarte do mioc\u00e1rdio atrav\u00e9s de uma interven\u00e7\u00e3o coron\u00e1ria percut\u00e2nea (ICP). Uma semana e meia depois, iniciou um programa de reabilita\u00e7\u00e3o cardiovascular em regime ambulat\u00f3rio. Durante a reabilita\u00e7\u00e3o, os factores de risco cardiovascular devem ser optimizados de forma a reduzir a probabilidade de recorr\u00eancia. Isto inclui a considera\u00e7\u00e3o de potenciais factores de impacto psicossocial. Por esta raz\u00e3o, o cardiologista tamb\u00e9m aborda o estado mental atual do doente durante o exame m\u00e9dico inicial e \u00e9 realizado um question\u00e1rio normalizado de rastreio de queixas psicol\u00f3gicas. O Sr. M. declarou que sofria de ansiedade parox\u00edstica recorrente, ins\u00f3nias, preocupa\u00e7\u00f5es graves e mau humor. O rastreio por question\u00e1rio confirmou estes sintomas e mostrou uma gravidade clinicamente relevante em compara\u00e7\u00e3o com a popula\u00e7\u00e3o normal. Com base nestas constata\u00e7\u00f5es, o cardiologista apresentou o doente \u00e0 consulta de cardiopsicologia e, com o consentimento do doente, organizou uma primeira consulta nessa consulta.<\/p>\n\n<p class=\"wp-block-paragraph\">A principal tarefa dos cuidados cardiopsicol\u00f3gicos especializados consiste em tratar as perturba\u00e7\u00f5es mentais com\u00f3rbidas em pessoas com doen\u00e7as cardiovasculares, a fim de reduzir o n\u00edvel de sofrimento e melhorar o progn\u00f3stico de sa\u00fade. A maior parte do tratamento \u00e9 efectuada em regime de ambulat\u00f3rio, embora os centros especializados possam tamb\u00e9m oferecer servi\u00e7os de consulta e de liga\u00e7\u00e3o adequados, bem como cuidados em regime de internamento.<\/p>\n\n<p class=\"wp-block-paragraph\">Queixas psicol\u00f3gicas como as relatadas pelo Sr. M. s\u00e3o comuns e ocorrem no contexto de v\u00e1rias doen\u00e7as cardiovasculares (por exemplo, s\u00edndrome coron\u00e1ria aguda ou cr\u00f3nica, insufici\u00eancia card\u00edaca, doen\u00e7as ritmog\u00e9nicas, defeitos card\u00edacos cong\u00e9nitos). Os exemplos de casos de cardiopsicologia s\u00e3o diversos e a popula\u00e7\u00e3o de doentes varia desde crian\u00e7as a idosos <strong>(Vis\u00e3o Geral 1)<\/strong>. As perturba\u00e7\u00f5es mentais que ocorrem frequentemente neste contexto s\u00e3o a perturba\u00e7\u00e3o de p\u00e2nico (F41.0), a agorafobia (F40.0X), os epis\u00f3dios depressivos (F32.XX), as perturba\u00e7\u00f5es de ajustamento (F43.2X), a perturba\u00e7\u00e3o de stress p\u00f3s-traum\u00e1tico (F43.1), a disfun\u00e7\u00e3o auton\u00f3mica somatoforme (F45.30) e a perturba\u00e7\u00e3o de stress som\u00e1tico (sensu DSM-5, c\u00f3digo de refer\u00eancia F45.1) [1].<\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht1_NP3_s6.png\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1268\" height=\"924\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht1_NP3_s6.png\" alt=\"\" class=\"wp-image-380229\" style=\"width:500px\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht1_NP3_s6.png 1268w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht1_NP3_s6-800x583.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht1_NP3_s6-1160x845.png 1160w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht1_NP3_s6-120x87.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht1_NP3_s6-90x66.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht1_NP3_s6-320x233.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht1_NP3_s6-560x408.png 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht1_NP3_s6-240x175.png 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht1_NP3_s6-180x131.png 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht1_NP3_s6-640x466.png 640w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht1_NP3_s6-1120x816.png 1120w\" sizes=\"(max-width: 1268px) 100vw, 1268px\" \/><\/a><\/figure>\n<\/div>\n<h3 id=\"prevalencias\" class=\"wp-block-heading\">Preval\u00eancias<\/h3>\n\n<p class=\"wp-block-paragraph\">[2,3]A preval\u00eancia anual de queixas psicol\u00f3gicas clinicamente relevantes \u00e9 de cerca de 40% em todos os grupos de doen\u00e7as cardiovasculares . At\u00e9 \u00e0 data, os estudos epidemiol\u00f3gicos t\u00eam-se centrado principalmente nas perturba\u00e7\u00f5es de ansiedade e nas perturba\u00e7\u00f5es depressivas. A preval\u00eancia de ambos os grupos de perturba\u00e7\u00f5es \u00e9 significativamente mais elevada nas pessoas com doen\u00e7as cardiovasculares do que na popula\u00e7\u00e3o em geral.<\/p>\n\n<p class=\"wp-block-paragraph\">An\u00e1lises mais diferenciadas mostram que a perturba\u00e7\u00e3o de ansiedade generalizada, a perturba\u00e7\u00e3o de p\u00e2nico e a agorafobia ocorrem mais frequentemente nas perturba\u00e7\u00f5es de ansiedade. Em compara\u00e7\u00e3o com a popula\u00e7\u00e3o em geral, a preval\u00eancia \u00e9 2,5 a 4,5 vezes superior [4]. As taxas de preval\u00eancia pontual de epis\u00f3dios depressivos com\u00f3rbidos s\u00e3o de 20% a 30% [5], o que corresponde a um aumento de 2 a 3 vezes em compara\u00e7\u00e3o com a popula\u00e7\u00e3o em geral [6].  <\/p>\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, os estudos indicam que as taxas de preval\u00eancia est\u00e3o relacionadas com a gravidade da doen\u00e7a cardiovascular. Foi demonstrado, por exemplo, que a preval\u00eancia pontual de perturba\u00e7\u00f5es depressivas em pessoas com insufici\u00eancia card\u00edaca aumenta com o aumento dos sintomas card\u00edacos. As pessoas com sintomas cardiovasculares ligeiros (fase I da NYHA) t\u00eam uma preval\u00eancia de 11%, enquanto as pessoas com sintomas cardiovasculares graves (fase IV da NYHA) t\u00eam uma preval\u00eancia de 42% [7].<\/p>\n\n<h3 id=\"relevancia-prognostica\" class=\"wp-block-heading\">Relev\u00e2ncia progn\u00f3stica<\/h3>\n\n<p class=\"wp-block-paragraph\">As perturba\u00e7\u00f5es mentais n\u00e3o est\u00e3o apenas associadas ao sofrimento, mas podem tamb\u00e9m influenciar significativamente o curso das doen\u00e7as cardiovasculares, com efeitos negativos na morbilidade e na mortalidade.<\/p>\n\n<p class=\"wp-block-paragraph\">Assim, um estudo realizado com 26 641 pessoas mostrou que o risco de morte aumenta significativamente se os sintomas depressivos e de ansiedade estiverem presentes durante 12 meses ap\u00f3s a sobreviv\u00eancia a um enfarte do mioc\u00e1rdio. O risco de morte cardiovascular foi aumentado em 46% e o risco de morte n\u00e3o-cardiovascular em 54% [8]. Do mesmo modo, as pessoas com insufici\u00eancia card\u00edaca e sintomas depressivos com\u00f3rbidos tamb\u00e9m t\u00eam um risco significativamente mais elevado de mortalidade e de eventos cardiovasculares secund\u00e1rios (cerca de 1,5 a 2,5 vezes mais) [9].<\/p>\n\n<p class=\"wp-block-paragraph\">[10]Al\u00e9m disso, dados meta-anal\u00edticos mostram que os sintomas de depress\u00e3o est\u00e3o associados a um aumento de 57% na probabilidade de eventos adversos e de 43% no risco de morte ap\u00f3s ICP. [11]Foi tamb\u00e9m demonstrada uma influ\u00eancia negativa dos sintomas de depress\u00e3o na mortalidade em opera\u00e7\u00f5es de bypass aortocoron\u00e1rio.  <\/p>\n\n<p class=\"wp-block-paragraph\">[12\u201314]Para al\u00e9m do impacto negativo no progn\u00f3stico som\u00e1tico, as pessoas com doen\u00e7as cardiovasculares e perturba\u00e7\u00f5es mentais t\u00eam tamb\u00e9m taxas de reinternamento e custos de tratamento significativamente mais elevados.<\/p>\n\n<h3 id=\"mecanismos-de-accao\" class=\"wp-block-heading\">Mecanismos de ac\u00e7\u00e3o<\/h3>\n\n<p class=\"wp-block-paragraph\">As interac\u00e7\u00f5es entre as perturba\u00e7\u00f5es mentais e as doen\u00e7as cardiovasculares podem ser explicadas por processos fisiol\u00f3gicos e comportamentais<strong> (Fig. 1) <\/strong>. Processos fisiol\u00f3gicos associados podem promover a ocorr\u00eancia combinada de doen\u00e7as cardiovasculares e perturba\u00e7\u00f5es mentais. Por exemplo, uma perturba\u00e7\u00e3o depressiva persistente pode provocar altera\u00e7\u00f5es no sistema nervoso aut\u00f3nomo que levam a um aumento do t\u00f3nus simp\u00e1tico e a um aumento do n\u00edvel de cortisol, o que tem um efeito negativo no sistema cardiovascular em termos de sobrecarga. [4,15]Inversamente, o aumento prolongado da ativa\u00e7\u00e3o do sistema cardiovascular e do sistema nervoso aut\u00f3nomo pode contribuir para o desenvolvimento de uma perturba\u00e7\u00e3o mental .<\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/abb1_NP3_s7.png\"><img decoding=\"async\" width=\"1792\" height=\"807\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/abb1_NP3_s7.png\" alt=\"\" class=\"wp-image-380228 lazyload\" style=\"--smush-placeholder-width: 1792px; --smush-placeholder-aspect-ratio: 1792\/807;width:500px\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/abb1_NP3_s7.png 1792w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/abb1_NP3_s7-800x360.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/abb1_NP3_s7-1160x522.png 1160w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/abb1_NP3_s7-120x54.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/abb1_NP3_s7-90x41.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/abb1_NP3_s7-320x144.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/abb1_NP3_s7-560x252.png 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/abb1_NP3_s7-240x108.png 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/abb1_NP3_s7-180x81.png 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/abb1_NP3_s7-640x288.png 640w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/abb1_NP3_s7-1120x504.png 1120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/abb1_NP3_s7-1600x721.png 1600w\" data-sizes=\"(max-width: 1792px) 100vw, 1792px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/a><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">Outros processos incluem altera\u00e7\u00f5es nos receptores e na fun\u00e7\u00e3o das plaquetas, no inibidor do ativador do plasminog\u00e9nio-1, no fibrinog\u00e9nio e nos processos de coagula\u00e7\u00e3o associados, na fun\u00e7\u00e3o endotelial, nas citocinas pr\u00f3-inflamat\u00f3rias (por exemplo, interleucina-6 e interleucina-10), em factores gen\u00e9ticos (por exemplo, o gene do transportador de serotonina), no t\u00f3nus parassimp\u00e1tico reduzido e na endocitose disfuncional. [IL-6] [IL-10] [16\u201318]A doen\u00e7a pode ser causada por factores gen\u00e9ticos (p. ex., interleucina-6 e interleucina-10), factores gen\u00e9ticos (p. ex., gene do transportador de serotonina), redu\u00e7\u00e3o do t\u00f3nus parassimp\u00e1tico e regula\u00e7\u00e3o disfuncional do feedback end\u00f3crino no eixo hipot\u00e1lamo-hip\u00f3fise-adrenal.<\/p>\n\n<p class=\"wp-block-paragraph\">O mesmo se aplica aos mecanismos comportamentais que podem ocorrer com maior frequ\u00eancia em ambos os grupos de doen\u00e7as e promover o risco de desenvolvimento ou agravamento da doen\u00e7a em ambas as direc\u00e7\u00f5es. Exemplos disso s\u00e3o o consumo de nicotina, uma dieta pouco saud\u00e1vel, a inatividade f\u00edsica e a ades\u00e3o \u00e0 medica\u00e7\u00e3o [2].<\/p>\n\n<h3 id=\"recomendacoes-de-tratamento\" class=\"wp-block-heading\">Recomenda\u00e7\u00f5es de tratamento<\/h3>\n\n<p class=\"wp-block-paragraph\">As perturba\u00e7\u00f5es mentais associadas \u00e0s doen\u00e7as cardiovasculares s\u00e3o tratadas tanto a n\u00edvel psicoterap\u00eautico como psicofarmacol\u00f3gico, consoante o tipo de perturba\u00e7\u00e3o e a sua gravidade. O tratamento baseia-se geralmente nas directrizes cl\u00e1ssicas para as perturba\u00e7\u00f5es mentais. No entanto, alguns aspectos do tratamento deste grupo espec\u00edfico de doentes devem ser objeto de especial aten\u00e7\u00e3o e adapta\u00e7\u00e3o.<\/p>\n\n<p class=\"wp-block-paragraph\">Se houver incertezas quanto aos efeitos cardiovasculares adversos no tratamento de perturba\u00e7\u00f5es mentais, \u00e9 essencial consultar especialistas em cardiologia. Deve ter especial cuidado no caso de doen\u00e7as cardiovasculares complexas. Exemplos de tais quadros cl\u00ednicos s\u00e3o a insufici\u00eancia card\u00edaca grave com poss\u00edvel transplante ou sistemas mec\u00e2nicos de suporte card\u00edaco (por exemplo,<em> dispositivo de assist\u00eancia ventricular esquerda, <\/em>LVAD), arritmias malignas e defeitos card\u00edacos cong\u00e9nitos complexos. Nestes casos, recomenda-se o tratamento num centro especializado se houver uma perturba\u00e7\u00e3o mental concomitante. Isto permite um interc\u00e2mbio efetivo entre as diferentes especialidades da medicina cardiovascular e da psicologia cl\u00ednica\/psiquiatria. O pessoal especializado destes centros possui um conhecimento aprofundado tanto das perturba\u00e7\u00f5es mentais como das doen\u00e7as cardiovasculares. Esta experi\u00eancia permite um tratamento especializado dos sintomas psicol\u00f3gicos, adaptado \u00e0s necessidades deste grupo espec\u00edfico de pacientes, tanto a n\u00edvel psicofarmacol\u00f3gico como psicoterap\u00eautico. As recomenda\u00e7\u00f5es de tratamento espec\u00edficas mais importantes para este contexto est\u00e3o resumidas na<strong> Vis\u00e3o Geral 2 <\/strong>.<\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht2_NP3_s8.png\"><img decoding=\"async\" width=\"1254\" height=\"1144\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht2_NP3_s8.png\" alt=\"\" class=\"wp-image-380230 lazyload\" style=\"--smush-placeholder-width: 1254px; --smush-placeholder-aspect-ratio: 1254\/1144;width:500px\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht2_NP3_s8.png 1254w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht2_NP3_s8-800x730.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht2_NP3_s8-1160x1058.png 1160w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht2_NP3_s8-120x109.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht2_NP3_s8-90x82.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht2_NP3_s8-320x292.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht2_NP3_s8-560x511.png 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht2_NP3_s8-240x219.png 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht2_NP3_s8-180x164.png 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht2_NP3_s8-640x584.png 640w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht2_NP3_s8-1120x1022.png 1120w\" data-sizes=\"(max-width: 1254px) 100vw, 1254px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/a><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">No que diz respeito aos tratamentos psicofarmacol\u00f3gicos, um poss\u00edvel prolongamento do intervalo QTc, efeitos sobre a anticoagula\u00e7\u00e3o e sobre a tens\u00e3o arterial s\u00e3o de particular relev\u00e2ncia. O prolongamento do intervalo QTc pode, em certos casos, levar a fibrilha\u00e7\u00e3o ventricular com risco de vida devido a um atraso na repolariza\u00e7\u00e3o ventricular. As prepara\u00e7\u00f5es que podem prolongar o intervalo QTc s\u00e3o os inibidores selectivos da recapta\u00e7\u00e3o da serotonina (SSRIs), os inibidores selectivos da recapta\u00e7\u00e3o da serotonina-norepinefrina (SSNRIs), os antidepressivos tric\u00edclicos (TCAs), os antipsic\u00f3ticos da classe 1. e [19,20]2\u00aa gera\u00e7\u00e3o e l\u00edtio . Especialmente em pessoas com doen\u00e7as subjacentes ritmog\u00e9nicas (por exemplo, s\u00edndrome do QT longo), deve consultar especialistas em cardiologia e efetuar controlos ECG adequados.<\/p>\n\n<p class=\"wp-block-paragraph\">A anticoagula\u00e7\u00e3o deve ser tida em conta, especialmente com prepara\u00e7\u00f5es serotonin\u00e9rgicas, uma vez que estas podem aumentar o risco de hemorragia devido a uma redu\u00e7\u00e3o da ativa\u00e7\u00e3o e agrega\u00e7\u00e3o plaquet\u00e1ria relacionada com a serotonina. As an\u00e1lises actuais mostram que o risco de hemorragia aumenta em cerca de 35% a 45% nas pessoas que tomam simultaneamente um SSRI e uma terapia antitromb\u00f3tica (anticoagulantes ou agentes antiplaquet\u00e1rios) em compara\u00e7\u00e3o com as pessoas que apenas recebem terapia antitromb\u00f3tica. Por conseguinte, deve ter cuidado ao prescrever um SSRI a pessoas que estejam a receber terapia antitromb\u00f3tica. [21,22]Em caso de anticoagula\u00e7\u00e3o forte (por exemplo, com uma v\u00e1lvula card\u00edaca mec\u00e2nica), a coagula\u00e7\u00e3o sangu\u00ednea deve ser monitorizada de perto durante a fase de dosagem.<\/p>\n\n<p class=\"wp-block-paragraph\">As altera\u00e7\u00f5es da tens\u00e3o arterial devem ser tidas em conta, nomeadamente com as prepara\u00e7\u00f5es noradren\u00e9rgicas. [19]Estes incluem os inibidores da recapta\u00e7\u00e3o da noradrenalina (NRI), os SSNRI e os inibidores da recapta\u00e7\u00e3o da noradrenalina e da dopamina (NDRI) . Isto \u00e9 extremamente importante para as pessoas em que uma subida significativa da press\u00e3o arterial pode ser agudamente amea\u00e7adora, como \u00e9 o caso das pessoas com doen\u00e7as do tecido conjuntivo que podem levar a dissec\u00e7\u00f5es da aorta (por exemplo, s\u00edndrome de Marfan).<\/p>\n\n<p class=\"wp-block-paragraph\">O uso de TCAs e estimulantes n\u00e3o \u00e9 geralmente recomendado para pessoas com doen\u00e7as cardiovasculares. Os TCAs apresentam um risco comparativamente elevado de prolongamento do intervalo QTc. Al\u00e9m disso, o efeito anticolin\u00e9rgico destes medicamentos pode ser prejudicial em pessoas com doen\u00e7as cardiovasculares. [3,19]A principal raz\u00e3o para isto \u00e9 o poss\u00edvel stress adicional no sistema cardiovascular devido \u00e0 inibi\u00e7\u00e3o do sistema parassimp\u00e1tico atrav\u00e9s do bloqueio do efeito da acetilcolina nos receptores muscar\u00ednicos da acetilcolina, bem como potenciais altera\u00e7\u00f5es na press\u00e3o sangu\u00ednea e vasodilata\u00e7\u00e3o\/constri\u00e7\u00e3o .<\/p>\n\n<p class=\"wp-block-paragraph\">Estimulantes como o metilfenidato, que s\u00e3o utilizados para tratar a perturba\u00e7\u00e3o de d\u00e9fice de aten\u00e7\u00e3o\/hiperatividade (PHDA), t\u00eam sido relatados como causadores de morte s\u00fabita em pessoas com doen\u00e7as cardiovasculares. [23,24]Por conseguinte, a doen\u00e7a cardiovascular \u00e9 considerada uma contraindica\u00e7\u00e3o, embora estudos recentes mostrem que o risco pode ter sido sobrestimado at\u00e9 \u00e0 data. Em alternativa, as subst\u00e2ncias bupropiona ou agomelatina podem ser consideradas como apoio farmacol\u00f3gico. Estes tendem a ter um efeito menor nos sintomas da PHDA, mas oferecem um perfil de risco cardiovascular significativamente mais favor\u00e1vel. [25\u201329]No entanto, a base de provas para a utiliza\u00e7\u00e3o destas prepara\u00e7\u00f5es como alternativa para a PHDA \u00e9 ainda muito limitada.<\/p>\n\n<p class=\"wp-block-paragraph\">\u00c9 tamb\u00e9m de salientar que, de acordo com as actuais directrizes cardiovasculares europeias, a administra\u00e7\u00e3o de SSRIs, SSNRIs e TCAs com uma recomenda\u00e7\u00e3o IIIB n\u00e3o \u00e9 recomendada em pessoas com insufici\u00eancia card\u00edaca [3]. Isto deve-se ao facto de estudos maiores terem demonstrado um ligeiro aumento da mortalidade com a administra\u00e7\u00e3o destas prepara\u00e7\u00f5es e nenhum efeito empiricamente comprovado sobre os sintomas depressivos. [30\u201332]Assim, com base no estado atual dos conhecimentos, n\u00e3o existe uma rela\u00e7\u00e3o custo-benef\u00edcio emp\u00edrica leg\u00edtima. [28]No entanto, o caso individual deve ser sempre considerado cuidadosamente e o benef\u00edcio potencial e o risco esperado devem ser ponderados individualmente e numa base interdisciplinar, a fim de utilizar as melhores op\u00e7\u00f5es de tratamento poss\u00edveis.<\/p>\n\n<p class=\"wp-block-paragraph\">Deve tamb\u00e9m ser dada especial aten\u00e7\u00e3o \u00e0 utiliza\u00e7\u00e3o de certos elementos de tratamento psicoterap\u00eautico n\u00e3o medicamentoso neste grupo de doentes. [33]Isto aplica-se a terapias de exposi\u00e7\u00e3o (por exemplo, para agorafobia, perturba\u00e7\u00e3o de stress p\u00f3s-traum\u00e1tico) em que uma forte ativa\u00e7\u00e3o emocional e fisiol\u00f3gica associada \u00e9 gerada atrav\u00e9s de confronta\u00e7\u00e3o in-vivo ou in-sensu . Esta interven\u00e7\u00e3o n\u00e3o \u00e9 recomendada em pessoas com doen\u00e7a card\u00edaca coron\u00e1ria e vasos n\u00e3o totalmente revascularizados ou em pessoas em que uma forte ativa\u00e7\u00e3o vegetativa pode ser agudamente amea\u00e7adora (por exemplo, certas arritmias malignas ou com potencial para dissec\u00e7\u00e3o da aorta). Nestes casos, recomenda-se vivamente a consulta de um especialista em cardiologia. As alternativas terap\u00eauticas poss\u00edveis s\u00e3o as abordagens metacognitivas e as interven\u00e7\u00f5es da terapia de aceita\u00e7\u00e3o e compromisso (ACT). [34,35]Estas centram-se na mudan\u00e7a da forma como as pessoas lidam com os pensamentos e emo\u00e7\u00f5es que surgem e s\u00e3o fisiologicamente menos activadoras do que as terapias de exposi\u00e7\u00e3o, embora sejam necess\u00e1rias mais provas para garantir a efic\u00e1cia emp\u00edrica destas alternativas neste contexto.<\/p>\n\n<h3 id=\"eficacia-das-intervencoes\" class=\"wp-block-heading\">Efic\u00e1cia das interven\u00e7\u00f5es<\/h3>\n\n<p class=\"wp-block-paragraph\">As interven\u00e7\u00f5es psicoterap\u00eauticas n\u00e3o farmacol\u00f3gicas revelam um grau de efic\u00e1cia relevante no que diz respeito aos sintomas psicol\u00f3gicos nesta popula\u00e7\u00e3o de doentes, sendo que as abordagens terap\u00eauticas cognitivo-comportamentais t\u00eam sido as mais investigadas at\u00e9 \u00e0 data. [36\u201339]No que respeita \u00e0 depress\u00e3o e \u00e0 ansiedade, as revis\u00f5es mostram um efeito meta-anal\u00edtico de cerca de 0,3 (SMD) em cada caso. [37]Foi igualmente demonstrado que as interven\u00e7\u00f5es psicol\u00f3gicas podem estar associadas a uma redu\u00e7\u00e3o da mortalidade at\u00e9 21% num prazo de dez anos. No entanto, o efeito das interven\u00e7\u00f5es psicol\u00f3gicas na morbilidade e mortalidade som\u00e1ticas requer ainda mais investiga\u00e7\u00e3o.<\/p>\n\n<p class=\"wp-block-paragraph\">As terapias psicofarmacol\u00f3gicas tamb\u00e9m t\u00eam um efeito sobre os sintomas psicol\u00f3gicos neste grupo de pacientes e h\u00e1 tamb\u00e9m indica\u00e7\u00f5es de influ\u00eancias positivas sobre o curso som\u00e1tico [3]. [40]No entanto, dados recentes sugerem tamb\u00e9m efeitos potencialmente negativos dos tratamentos psicofarmacol\u00f3gicos a longo prazo no sistema cardiovascular.<\/p>\n\n<p class=\"wp-block-paragraph\">[41]Os dados actuais n\u00e3o revelam qualquer superioridade geral de uma das duas formas de tratamento (medica\u00e7\u00e3o vs. n\u00e3o medica\u00e7\u00e3o) em pessoas com doen\u00e7as cardiovasculares e perturba\u00e7\u00f5es mentais co-m\u00f3rbidas. Por conseguinte, o melhor tratamento poss\u00edvel deve ser selecionado em consulta com a pessoa em causa e num di\u00e1logo interdisciplinar, tendo em conta os sintomas individuais, as condi\u00e7\u00f5es contextuais e as recomenda\u00e7\u00f5es de tratamento pertinentes. Um tratamento flex\u00edvel e integrador, com uma avalia\u00e7\u00e3o correcta e regular do progresso, \u00e9 de import\u00e2ncia fulcral.<\/p>\n\n<h3 id=\"resumo\" class=\"wp-block-heading\">Resumo<\/h3>\n\n<p class=\"wp-block-paragraph\">As perturba\u00e7\u00f5es mentais s\u00e3o relativamente frequentes em pessoas com doen\u00e7as cardiovasculares. As perturba\u00e7\u00f5es mentais s\u00e3o relevantes em termos de progn\u00f3stico e podem ter um impacto negativo na evolu\u00e7\u00e3o das doen\u00e7as cardiovasculares. As interac\u00e7\u00f5es entre as perturba\u00e7\u00f5es mentais e as doen\u00e7as cardiovasculares devem-se a processos fisiol\u00f3gicos (por exemplo, processos hormonais e inflamat\u00f3rios) e a processos comportamentais (por exemplo, comportamento de exerc\u00edcio, consumo de subst\u00e2ncias). O tratamento das perturba\u00e7\u00f5es mentais nas pessoas com doen\u00e7as cardiovasculares pode ser efectuado tanto a n\u00edvel farmacol\u00f3gico como psicoterap\u00eautico, devendo ser tidas em conta as recomenda\u00e7\u00f5es espec\u00edficas de tratamento e os acordos interdisciplinares. Sobretudo no caso de doen\u00e7as cardiovasculares mais complexas e de perturba\u00e7\u00f5es mentais co-m\u00f3rbidas, o tratamento deve ser efectuado, sempre que poss\u00edvel, em centros especializados. Gra\u00e7as ao seu foco especializado, estes centros facilitam a colabora\u00e7\u00e3o interdisciplinar e podem oferecer op\u00e7\u00f5es de tratamento mais espec\u00edficas para este grupo de doentes. As interven\u00e7\u00f5es psicoterap\u00eauticas e psicofarmacol\u00f3gicas s\u00e3o eficazes na redu\u00e7\u00e3o das queixas psicol\u00f3gicas. Ambas as abordagens de tratamento tamb\u00e9m mostraram indica\u00e7\u00f5es iniciais de efeitos positivos no curso cardiovascular.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Mensagens para levar para casa<\/strong><\/p>\n\n<ul class=\"wp-block-list\">\n<li>As perturba\u00e7\u00f5es mentais surgem frequentemente no contexto de doen\u00e7as cardiovasculares.<\/li>\n\n\n\n<li>As perturba\u00e7\u00f5es mentais podem ter um impacto negativo no progn\u00f3stico som\u00e1tico.<\/li>\n\n\n\n<li>Existem abordagens eficazes para tratar as queixas psicol\u00f3gicas.<\/li>\n\n\n\n<li>No tratamento das queixas psicol\u00f3gicas, deve ter em conta recomenda\u00e7\u00f5es espec\u00edficas.  <\/li>\n\n\n\n<li>As pessoas com doen\u00e7as cardiovasculares complexas e perturba\u00e7\u00f5es mentais com\u00f3rbidas devem ser tratadas em centros especializados.<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\">Literatura:<\/p>\n\n<ol class=\"wp-block-list\">\n<li>Herrmann-Lingen C, Albus C, Titscher G: Psychokardiologie. Ein Praxisleitfaden f\u00fcr \u00c4rzte und Psychologen K\u00f6ln: Deutscher \u00c4rzte-Verlag. 2008.<\/li>\n\n\n\n<li>Albus C, Waller C, Fritzsche K, et al.: Significance of psychosocial factors in cardiology: update 2018: Position paper of the German Cardiac Society. Clin Res Cardiol 2019; 108(11): 1175\u20131196.<\/li>\n\n\n\n<li>Visseren FLJ, Mach F, Smulders YM, et al.: 2021 ESC Guidelines on cardiovascular disease prevention in clinical practice. Eur Heart J 2021; 42(34): 3227\u20133337.<\/li>\n\n\n\n<li>Pedersen SS, Von K\u00e4nel R, Tully PJ, Denollet J: Psychosocial perspectives in cardiovascular disease. European journal of preventive cardiology 2017; 24(3_suppl): 108\u2013115.<\/li>\n\n\n\n<li>Gold SM, Kohler-Forsberg O, Moss-Morris R, et al.: Comorbid depression in medical diseases. Nat Rev Dis Primers 2020;6(1): 69.<\/li>\n\n\n\n<li>Wittchen HU, Jacobi F, Rehm J, et al.: The size and burden of mental disorders and other disorders of the brain in Europe 2010. Eur Neuropsychopharmacol 2011; 21(9): 655\u2013679.<\/li>\n\n\n\n<li>Rutledge T, Reis VA, Linke SE, et al.: Depression in heart failure a meta-analytic review of prevalence, intervention effects, and associations with clinical outcomes. J Am Coll Cardiol. 2006;48(8):1527-37.<\/li>\n\n\n\n<li>Lissaker CT, Norlund F, Wallert J, et al.: Persistent emotional distress after a first-time myocardial infarction and its association to late cardiovascular and non-cardiovascular mortality. Eur J Prev Cardiol 2019; 26(14): 1510\u20131518.<\/li>\n\n\n\n<li>Sbolli M, Fiuzat M, Cani D, O\u2019Connor CM: Depression and heart failure: the lonely comorbidity. Eur J Heart Fail 2020; 22(11): 2007\u20132017.<\/li>\n\n\n\n<li>Zhang WY, Nan N, Song XT, et al.: Impact of depression on clinical outcomes following percutaneous coronary intervention: a systematic review and meta-analysis. BMJ Open 2019; 9(8): e026445.<\/li>\n\n\n\n<li>Geulayov G, Novikov I, Dankner D, Dankner R: Symptoms of depression and anxiety and 11-year all-cause mortality in men and women undergoing coronary artery bypass graft (CABG) surgery. J Psychosom Res. 2018; 105: 106\u2013114.<\/li>\n\n\n\n<li>Frasure-Smith N, Lesp\u00e9rance F, Gravel G, et al.: Depression and health-care costs during the first year following myocardial infarction. Journal of Psychosomatic Research 2000: 471\u2013478.<\/li>\n\n\n\n<li>Jha MK, Qamar A, Vaduganathan M, et al.: Screening and Management of Depression in Patients With Cardiovascular Disease: JACC State-of-the-Art Review. J Am Coll Cardiol 2019;73(14): 1827\u20131845.<\/li>\n\n\n\n<li>Vaccarino V, Badimon L, Bremner JD, et al.: Depression and coronary heart disease: 2018 position paper of the ESC working group on coronary pathophysiology and microcirculation. Eur Heart J 2020; 41(17): 1687\u20131696.<\/li>\n\n\n\n<li>Hare DL, Toukhsati SR, Johansson P, Jaarsma T: Depression and cardiovascular disease: a clinical review. Eur Heart J 2014; 35(21): 1365\u20131372.<\/li>\n\n\n\n<li>Meyer T, Stanske B, Kochen MM, et al.: Serum levels of interleukin-6 and interleukin-10 in relation to depression scores in patients with cardiovascular risk factors. Behav Med 2011;37(3): 105\u2013112.<\/li>\n\n\n\n<li>Liu RH, Pan JQ, Tang XE, et al.: The role of immune abnormality in depression and cardiovascular disease. J Geriatr Cardiol 2017; 14(11): 703\u2013110.<\/li>\n\n\n\n<li>Grippo AJ, Johnson AK: Stress, depression and cardiovascular dysregulation: a review of neurobiological mechanisms and the integration of research from preclinical disease models. Stress 2009; 12(1): 1\u201321.<\/li>\n\n\n\n<li>Pina IL, Di Palo KE, Ventura HO: Psychopharmacology and Cardiovascular Disease. J Am Coll Cardiol 2018; 71(20): 2346\u20132359.<\/li>\n\n\n\n<li>Mehta N, Vannozzi R: Lithium-induced electrocardiographic changes: A complete review. Clin Cardiol 2017; 40(12): 1363\u20131367.<\/li>\n\n\n\n<li>Nochaiwong S, Ruengorn C, Awiphan R, et al.: Use of serotonin reuptake inhibitor antidepressants and the risk of bleeding complications in patients on anticoagulant or antiplatelet agents: a systematic review and meta-analysis. Ann Med 2022; 54(1): 80\u201397.<\/li>\n\n\n\n<li>Rahman AA, He N, Rej S, et al.: Concomitant Use of Selective Serotonin Reuptake Inhibitors and Oral Anticoagulants and Risk of Major Bleeding: A Systematic Review and Meta-analysis. Thromb Haemost 2023; 123(1): 54\u201363.<\/li>\n\n\n\n<li>Garcia-Argibay M, Burkner PC, Lichtenstein P, et al.: Methylphenidate and Short-Term Cardiovascular Risk. JAMA Netw Open 2024;7(3): e241349.<\/li>\n\n\n\n<li>Jackson JW: The cardiovascular safety of methylphenidate. BMJ 2016; 353: i2874.<\/li>\n\n\n\n<li>Verbeeck W, Bekkering GE, Van den Noortgate W, Kramers C: Bupropion for attention deficit hyperactivity disorder (ADHD) in adults. Cochrane Database Syst Rev 2017; 10(10): CD009504.<\/li>\n\n\n\n<li>Salardini E, Zeinoddini A, Kohi A, et al.: Agomelatine as a Treatment for Attention-Deficit\/Hyperactivity Disorder in Children and Adolescents: A Double-Blind, Randomized Clinical Trial. J Child Adolesc Psychopharmacol. 2016;26(6): 513\u2013519.<\/li>\n\n\n\n<li>Niederhofer H: Treating ADHD with agomelatine. J Atten Disord 2012; 16(4): 346\u2013348.<\/li>\n\n\n\n<li>Ladwig KH, Baghai TC, Doyle F, et al: Mental health-related risk factors and interventions in patients with heart failure: a position paper endorsed by the European Association of Preventive Cardiology (EAPC). Eur J Prev Cardiol 2022; 29(7): 1124-1141.<\/li>\n\n\n\n<li>Behlke LM, Lenze EJ, Carney RM: The Cardiovascular Effects of Newer Antidepressants in Older Adults and Those With or At High Risk for Cardiovascular Diseases. CNS Drugs 2020; 34(11): 1133\u20131147.<\/li>\n\n\n\n<li>He W, Zhou Y, Ma J, et al.: Effect of antidepressants on death in patients with heart failure: a systematic review and meta-analysis. Heart Fail Rev 2020;25(6): 919\u2013926.<\/li>\n\n\n\n<li>Angermann CE, Gelbrich G, Stork S, et al.: Effect of Escitalopram on All-Cause Mortality and Hospitalization in Patients With Heart Failure and Depression: The MOOD-HF Randomized Clinical Trial. JAMA 2016; 315(24): 2683\u20132693.<\/li>\n\n\n\n<li>O\u2019Connor CM, Jiang W, Kuchibhatla M, et al.: Safety and efficacy of sertraline for depression in patients with heart failure: results of the SADHART-CHF (Sertraline Against Depression and Heart Disease in Chronic Heart Failure) trial. J Am Coll Cardiol 2010; 56(9): 692\u2013699.<\/li>\n\n\n\n<li>Bandelow B, Aden I, Alpers GW, et al.: Deutsche S3-Leitlinie Behandlung von Angstst\u00f6rungen, Version 2 (2021). 2021.<\/li>\n\n\n\n<li>Wells A, Reeves D, Heal C, et al.: Evaluating Metacognitive Therapy to Improve Treatment of Anxiety and Depression in Cardiovascular Disease: The NIHR Funded PATHWAY Research Programme. Front Psychiatry 2022; 13: 886407.<\/li>\n\n\n\n<li>Rashidi A, Whitehead L, Newson L, et al.: The Role of Acceptance and Commitment Therapy in Cardiovascular and Diabetes Healthcare: A Scoping Review. Int J Environ Res Public Health 2021;1 8(15).<\/li>\n\n\n\n<li>Reavell J, Hopkinson M, Clarkesmith D, Lane DA: Effectiveness of Cognitive Behavioral Therapy for Depression and Anxiety in Patients With Cardiovascular Disease: A Systematic Review and Meta-Analysis. Psychosom Med 2018; 80(8): 742\u2013753.<\/li>\n\n\n\n<li>Richards SH, Anderson L, Jenkinson CE, et al.: Psychological interventions for coronary heart disease. Cochrane Database Syst Rev 2017;4(4): CD002902.<\/li>\n\n\n\n<li>Chernoff RA, Messineo G, Kim S, et al.: Psychosocial Interventions for Patients With Heart Failure and Their Impact on Depression, Anxiety, Quality of Life, Morbidity, and Mortality: A Systematic Review and Meta-Analysis. Psychosom Med 2022; 84(5): 560\u2013580.<\/li>\n\n\n\n<li>Das A, Roy B, Schwarzer G, et al.: Comparison of treatment options for depression in heart failure: A network meta-analysis. J Psychiatr Res 2019; 108: 7\u201323.<\/li>\n\n\n\n<li>Cao H, Baranova A, Zhao Q, Zhang F: Bidirectional associations between mental disorders, antidepressants and cardiovascular disease. BMJ Ment Health 2024; 27(1).<\/li>\n\n\n\n<li>Zambrano J, Celano CM, Januzzi JL, et al.: Psychiatric and Psychological Interventions for Depression in Patients With Heart Disease: A Scoping Review. J Am Heart Assoc 2020;9(22): e018686.<\/li>\n<\/ol>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"has-small-font-size wp-block-paragraph\"><em>InFo NEUROLOGIE  PSYCHIATRIE 2024; 22(3): 6\u201310<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>As perturba\u00e7\u00f5es mentais ocorrem frequentemente no contexto de doen\u00e7as cardiovasculares e podem ter um impacto negativo no progn\u00f3stico som\u00e1tico. Regra geral, no entanto, existem abordagens eficazes para tratar estas queixas.&hellip;<\/p>\n","protected":false},"author":7,"featured_media":380549,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Cardiopsicologia","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11367,11521,22618,11305,11481,11551],"tags":[76643,14717,14969],"powerkit_post_featured":[],"class_list":["post-380548","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cardiologia-pt-pt","category-estudos","category-formacao-cme","category-medicina-interna-geral","category-psiquiatria-e-psicoterapia","category-rx-pt","tag-cardiopsicologia-pt-pt","tag-depressao","tag-perturbacoes-mentais","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 05:37:13","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"pt_PT","wpml_translations":{"es_ES":{"locale":"es_ES","id":380551,"slug":"la-psicologia-clinica-en-el-contexto-de-las-enfermedades-cardiovasculares","post_title":"La psicolog\u00eda cl\u00ednica en el contexto de las enfermedades cardiovasculares","href":"https:\/\/medizinonline.com\/es\/la-psicologia-clinica-en-el-contexto-de-las-enfermedades-cardiovasculares\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/380548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=380548"}],"version-history":[{"count":2,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/380548\/revisions"}],"predecessor-version":[{"id":383343,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/380548\/revisions\/383343"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media\/380549"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=380548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category?post=380548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=380548"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/powerkit_post_featured?post=380548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}