{"id":390381,"date":"2024-11-29T00:01:00","date_gmt":"2024-11-28T23:01:00","guid":{"rendered":"https:\/\/medizinonline.com\/?p=390381"},"modified":"2024-11-22T10:20:49","modified_gmt":"2024-11-22T09:20:49","slug":"atualizacao-sobre-o-diagnostico-da-doenca-de-alzheimer-foco-no-liquido-cefalorraquidiano-e-nos-biomarcadores-baseados-no-sangue-2","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/pt-pt\/atualizacao-sobre-o-diagnostico-da-doenca-de-alzheimer-foco-no-liquido-cefalorraquidiano-e-nos-biomarcadores-baseados-no-sangue-2\/","title":{"rendered":"Atualiza\u00e7\u00e3o sobre o diagn\u00f3stico da doen\u00e7a de Alzheimer: foco no l\u00edquido cefalorraquidiano e nos biomarcadores baseados no sangue"},"content":{"rendered":"\n<p><strong>Apesar da frequ\u00eancia e da import\u00e2ncia da doen\u00e7a de Alzheimer, em muitos casos esta n\u00e3o \u00e9 diagnosticada ou s\u00f3 \u00e9 diagnosticada numa fase avan\u00e7ada da doen\u00e7a, o que limita consideravelmente as op\u00e7\u00f5es de tratamento. Os marcadores moleculares do LCR, como a amiloide beta 1-42 (A\u03b21-42), a tau total (tau) e a tau fosforilada (pTau181), ou as t\u00e9cnicas de imagiologia, como a PET amiloide, s\u00e3o considerados m\u00e9todos de diagn\u00f3stico fi\u00e1veis que permitem a dete\u00e7\u00e3o precoce da patologia central da doen\u00e7a de Alzheimer. Num futuro pr\u00f3ximo, os biomarcadores baseados no sangue poder\u00e3o tornar-se cada vez mais importantes e facilitar muito o diagn\u00f3stico, uma vez que representam uma alternativa facilmente acess\u00edvel e mais econ\u00f3mica.<\/strong><\/p>\n\n\n\n<!--more-->\n\n\n\n<div class=\"cnvs-block-alert cnvs-block-alert-1669013560583\" >\n\t<div class=\"cnvs-block-alert-inner\">\n\t\t\n\n<p>Pode fazer o teste CME na nossa plataforma de aprendizagem depois de rever os materiais recomendados. Clique no bot\u00e3o seguinte:<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-a89b3969 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/academy.medizinonline.com\/course\/alzheimer-amyotrophe-lateralsklerose\" target=\"_blank\" rel=\"noreferrer noopener\">Inicie o teste CME<\/a><\/div>\n<\/div>\n\n\t<\/div>\n\t<\/div>\n\n\n\n<p>A doen\u00e7a de Alzheimer \u00e9 a causa mais comum de dem\u00eancia e \u00e9 considerada um dos maiores desafios individuais, sociais e de pol\u00edtica de sa\u00fade do nosso tempo. Apesar da frequ\u00eancia e da import\u00e2ncia da doen\u00e7a, em muitos casos ela n\u00e3o \u00e9 diagnosticada ou s\u00f3 \u00e9 diagnosticada numa fase avan\u00e7ada da doen\u00e7a, o que limita consideravelmente as op\u00e7\u00f5es de tratamento.<\/p>\n\n\n\n<p>Os marcadores moleculares do LCR, como a amiloide beta 1-42 (A\u03b21-42), a tau total (tau) e a tau fosforilada (pTau181), ou as t\u00e9cnicas de imagiologia, como a PET amiloide, s\u00e3o considerados m\u00e9todos de diagn\u00f3stico fi\u00e1veis que permitem a dete\u00e7\u00e3o precoce da patologia central da doen\u00e7a de Alzheimer. Est\u00e3o a ser utilizados cada vez com mais frequ\u00eancia e permitem fazer diagn\u00f3sticos e progn\u00f3sticos mais precisos, bem como recomenda\u00e7\u00f5es de tratamento personalizadas. No entanto, os resultados destes testes t\u00eam de ser interpretados cuidadosamente, individualmente e no contexto geral de todos os outros achados.    <\/p>\n\n\n\n<p>Num futuro pr\u00f3ximo, os biomarcadores baseados no sangue poder\u00e3o tornar-se cada vez mais importantes e facilitar muito o diagn\u00f3stico, uma vez que representam uma alternativa facilmente acess\u00edvel e mais econ\u00f3mica. Esta evolu\u00e7\u00e3o poder\u00e1 conduzir a uma utiliza\u00e7\u00e3o muito mais alargada dos biomarcadores e acelerar o desenvolvimento de abordagens de preven\u00e7\u00e3o e tratamento eficazes e personalizadas. <\/p>\n\n\n\n[38]Este artigo apresenta uma panor\u00e2mica abrangente do estado atual do diagn\u00f3stico da doen\u00e7a de Alzheimer, com destaque para os biomarcadores baseados no l\u00edquido cefalorraquidiano e no sangue. Al\u00e9m disso, \u00e9 explicada a import\u00e2ncia do diagn\u00f3stico precoce baseado em biomarcadores e \u00e9 discutida a perspetiva de poss\u00edveis desenvolvimentos no diagn\u00f3stico, especialmente no que diz respeito aos marcadores sangu\u00edneos. <\/p>\n\n\n\n<h3 id=\"introducao\" class=\"wp-block-heading\">Introdu\u00e7\u00e3o<\/h3>\n\n\n\n<p>Com mais de 156.900 pessoas diretamente afectadas na Su\u00ed\u00e7a hoje em dia, um n\u00famero que dever\u00e1 duplicar at\u00e9 2050, a dem\u00eancia representa um dos maiores desafios sociais, econ\u00f3micos e de pol\u00edtica de sa\u00fade. [20] Todos os anos, cerca de 33.000 pessoas na Su\u00ed\u00e7a s\u00e3o diagnosticadas com dem\u00eancia, mas apenas cerca de metade destes casos s\u00e3o formalmente diagnosticados, geralmente apenas numa fase avan\u00e7ada. As diretrizes nacionais e internacionais recomendam um diagn\u00f3stico precoce no decurso da dem\u00eancia [38,9,20]. Isto permite que as causas revers\u00edveis e as doen\u00e7as mentais que as acompanham sejam reconhecidas e tratadas. Al\u00e9m disso, os tratamentos medicamentosos, especialmente para a doen\u00e7a de Alzheimer, s\u00e3o mais eficazes nas fases iniciais da dem\u00eancia. Se o diagn\u00f3stico for feito o mais cedo poss\u00edvel, as pessoas afectadas podem tamb\u00e9m ser mais bem envolvidas nos processos de tomada de decis\u00e3o, uma vez que a sua capacidade de julgamento ainda est\u00e1, normalmente, intacta no in\u00edcio da dem\u00eancia. Os doentes e os seus familiares podem, assim, ser aconselhados de forma mais espec\u00edfica e apoiados no seu planeamento no que diz respeito \u00e0 organiza\u00e7\u00e3o da vida futura, aos cuidados, aos aspectos financeiros e jur\u00eddicos.<\/p>\n\n\n\n<h3 id=\"clarificacao-do-diagnostico\" class=\"wp-block-heading\">Clarifica\u00e7\u00e3o do diagn\u00f3stico<\/h3>\n\n\n\n<p>A avalia\u00e7\u00e3o das perturba\u00e7\u00f5es cognitivas na velhice \u00e9 geralmente efectuada ap\u00f3s um exame inicial no consult\u00f3rio de um m\u00e9dico de cl\u00ednica geral, se houver suspeita de perturba\u00e7\u00e3o cognitiva. Ap\u00f3s um exame de rastreio cl\u00ednico e cognitivo, o doente pode ser encaminhado para uma avalia\u00e7\u00e3o especializada numa cl\u00ednica de mem\u00f3ria. Em etapas posteriores, \u00e9 avaliada a gravidade do d\u00e9fice cognitivo e quaisquer sintomas neuropsiqui\u00e1tricos n\u00e3o cognitivos associados e perturba\u00e7\u00f5es nas actividades da vida di\u00e1ria. Al\u00e9m disso, a etiologia dos sintomas presentes deve ser suficientemente esclarecida para que se possa oferecer o tratamento mais eficaz e o aconselhamento mais personalizado poss\u00edvel. Os exames habituais na <em>Cl\u00ednica da Mem\u00f3ria<\/em> incluem uma hist\u00f3ria cl\u00ednica pormenorizada do doente e de outras pessoas, um exame cl\u00ednico e testes neuropsicol\u00f3gicos pormenorizados. A imagiologia estrutural do c\u00e9rebro e as an\u00e1lises sangu\u00edneas para procurar doen\u00e7as ou perturba\u00e7\u00f5es sist\u00e9micas como causas prim\u00e1rias ou factores de exacerba\u00e7\u00e3o do d\u00e9fice cognitivo tamb\u00e9m fazem parte do diagn\u00f3stico padr\u00e3o. Se houver motivos de suspeita, est\u00e3o dispon\u00edveis testes adicionais para um diagn\u00f3stico mais preciso, incluindo an\u00e1lises sangu\u00edneas alargadas e especiais, EEG, diagn\u00f3sticos do sono, procedimentos de medicina nuclear, an\u00e1lises do l\u00edquido cefalorraquidiano e outros testes.      <\/p>\n\n\n\n<h3 id=\"doenca-de-alzheimer\" class=\"wp-block-heading\">Doen\u00e7a de Alzheimer<\/h3>\n\n\n\n<p>Nas perturba\u00e7\u00f5es cognitivas na velhice, <em> a doen\u00e7a de<\/em> Alzheimer <em>(<\/em> DA) \u00e9 a patologia cerebral subjacente mais comum em cerca de 60-70% dos casos e, por conseguinte, a causa mais comum de dem\u00eancia [43]. As altera\u00e7\u00f5es cerebrais carater\u00edsticas desenvolvem-se at\u00e9 duas d\u00e9cadas antes do aparecimento dos primeiros sintomas, com cada vez mais regi\u00f5es cerebrais a serem afectadas pela neurodegenera\u00e7\u00e3o e pela perda de fun\u00e7\u00e3o ao longo do tempo [43]. Sobretudo nas fases iniciais, o quadro cl\u00ednico \u00e9 variado e inespec\u00edfico e, em muitos casos, as perturba\u00e7\u00f5es mentais e comportamentais precedem os sintomas cognitivos ou ocorrem em simult\u00e2neo com eles [22,44].<\/p>\n\n\n\n<p>Durante muitos anos, foram utilizados crit\u00e9rios baseados principalmente na avalia\u00e7\u00e3o cl\u00ednica e neuropsicol\u00f3gica e na exclus\u00e3o de outras causas para diagnosticar a doen\u00e7a de Alzheimer [31,47]. Estes crit\u00e9rios, mesmo quando aplicados por especialistas, t\u00eam uma precis\u00e3o de diagn\u00f3stico relativamente baixa, levando a diagn\u00f3sticos incorrectos em 20\u201330% dos casos [34,38]. O diagn\u00f3stico diferencial pode ser particularmente dif\u00edcil nas fases iniciais da doen\u00e7a, devido aos quadros cl\u00ednicos diversos e inespec\u00edficos [43]. Um grande n\u00famero de outras doen\u00e7as psiqui\u00e1tricas, sist\u00e9micas e neurol\u00f3gicas pode tamb\u00e9m levar a sintomas que tamb\u00e9m ocorrem no contexto da DA.<\/p>\n\n\n\n<p><em>O d\u00e9fice cogn <\/em>itivo<em> ligeiro<\/em> (ICM, tamb\u00e9m conhecido como <em>perturba\u00e7\u00e3o neurocognitiva ligeira <\/em>[3]), definido como um d\u00e9fice cognitivo objetiv\u00e1vel sem preju\u00edzo das actividades quotidianas, corresponde \u00e0 &#8220;fase prodr\u00f3mica&#8221; da dem\u00eancia na doen\u00e7a de Alzheimer e dura geralmente v\u00e1rios anos. Em muitos casos, as pr\u00f3prias pessoas afectadas ou os seus familiares apercebem-se dos primeiros sintomas e contactam diretamente o seu m\u00e9dico de fam\u00edlia ou uma <em>cl\u00ednica de mem\u00f3ria<\/em> para obter esclarecimentos. No entanto, o diagn\u00f3stico e o progn\u00f3stico nesta fase s\u00e3o imprecisos sem a inclus\u00e3o de biomarcadores adicionais e t\u00eam uma sensibilidade e especificidade ainda mais baixas do que nas fases de dem\u00eancia em , raz\u00e3o pela qual os testes adicionais, como os marcadores do l\u00edquido cefalorraquidiano, desempenham frequentemente um papel importante nesta fase em particular [43].<\/p>\n\n\n\n<p>Se, para al\u00e9m dos d\u00e9fices cognitivos em v\u00e1rias \u00e1reas da cogni\u00e7\u00e3o, as actividades quotidianas, como fazer compras, cozinhar ou a mobilidade independente nos transportes p\u00fablicos, forem restringidas por um per\u00edodo superior a seis meses devido a um d\u00e9fice cognitivo, pode ser feito um diagn\u00f3stico cl\u00ednico formal de dem\u00eancia [47].<\/p>\n\n\n\n<p>O longo per\u00edodo de tempo que decorre entre o aparecimento dos primeiros sintomas e o diagn\u00f3stico de prov\u00e1vel ou poss\u00edvel doen\u00e7a de Alzheimer e a baixa especificidade dos crit\u00e9rios cl\u00ednicos para a doen\u00e7a de Alzheimer s\u00e3o limita\u00e7\u00f5es importantes para um diagn\u00f3stico precoce e diferencial exato, bem como para o progn\u00f3stico das perturba\u00e7\u00f5es cognitivas e, por conseguinte, para recomenda\u00e7\u00f5es e op\u00e7\u00f5es de tratamento personalizadas.<\/p>\n\n\n\n<p>As altera\u00e7\u00f5es cerebrais carater\u00edsticas da DA s\u00e3o a acumula\u00e7\u00e3o intraneuronal de prote\u00edna tau hiperfosforilada (emaranhados neurofibrilares) e os dep\u00f3sitos extracelulares de p\u00e9ptidos amil\u00f3ides sob a forma de placas, associados \u00e0 perda de sinapses e \u00e0 morte neuronal. A prova direta das patologias espec\u00edficas ainda s\u00f3 pode ser fornecida histopatologicamente post mortem. No entanto, est\u00e3o tamb\u00e9m dispon\u00edveis v\u00e1rios m\u00e9todos que detectam indiretamente estas altera\u00e7\u00f5es patol\u00f3gicas durante a vida do doente e que podem, portanto, ser utilizados na pr\u00e1tica cl\u00ednica. Estes m\u00e9todos podem ajudar a melhorar a precis\u00e3o do diagn\u00f3stico etiol\u00f3gico das perturba\u00e7\u00f5es cognitivas na velhice [9,38]. Atualmente, tanto os biomarcadores do LCR como a PET amiloide est\u00e3o autorizados na Su\u00ed\u00e7a para a dete\u00e7\u00e3o da patologia da doen\u00e7a de Alzheimer. A tomografia por emiss\u00e3o de positr\u00f5es com fluorodesoxiglucose (FDG-PET) pode detetar o hipometabolismo nas regi\u00f5es cerebrais afectadas pela perda de fun\u00e7\u00e3o e apresentar padr\u00f5es t\u00edpicos da doen\u00e7a de Alzheimer e de outras doen\u00e7as neurodegenerativas, melhorando assim o diagn\u00f3stico diferencial, sobretudo nas fases cl\u00ednicas iniciais. A PET amiloide pode ser utilizada para visualizar diretamente os dep\u00f3sitos de amiloide no c\u00e9rebro [25]. A Tau PET para a dete\u00e7\u00e3o in vivo da patologia da tau tem estado at\u00e9 agora dispon\u00edvel principalmente para fins de investiga\u00e7\u00e3o. A disponibilidade destes exames \u00e9 limitada pelos custos relativamente elevados, pela radioatividade associada e pela necessidade de os realizar em centros de medicina nuclear.<\/p>\n\n\n\n<p>Os biomarcadores do LCR s\u00e3o analisados mais pormenorizadamente a seguir.<\/p>\n\n\n\n<h3 id=\"os-marcadores-estabelecidos-no-lcr-das-doencas-neurodegenerativas\" class=\"wp-block-heading\">Os marcadores estabelecidos no LCR das doen\u00e7as neurodegenerativas<\/h3>\n\n\n\n<p>Os marcadores do LCR s\u00e3o utilizados para avaliar as perturba\u00e7\u00f5es cognitivas h\u00e1 mais de 20 anos. Fazem parte das recomenda\u00e7\u00f5es consensuais su\u00ed\u00e7as e internacionais [9,38]. As raz\u00f5es para tal s\u00e3o a necessidade de uma maior precis\u00e3o no diagn\u00f3stico e o esfor\u00e7o para confirmar o diagn\u00f3stico mesmo em perturba\u00e7\u00f5es ligeiras (MCI) e na presen\u00e7a de sintomas at\u00edpicos para a DA e, assim, oferecer recomenda\u00e7\u00f5es espec\u00edficas para o tratamento, o planeamento da vida e a preven\u00e7\u00e3o secund\u00e1ria numa fase precoce [39,43].<\/p>\n\n\n\n<p>Os biomarcadores moleculares do LCR amiloide-beta 1-42 (A\u03b21-42), tau total (tau) e tau hiperfosforilada na treonina 181 (pTau181) reflectem a deposi\u00e7\u00e3o de amiloide cerebral, a morte de c\u00e9lulas neuronais e a patologia neurofibrilar, respetivamente. \u00c0 medida que estas prote\u00ednas se aglomeram e acumulam no c\u00e9rebro, a concentra\u00e7\u00e3o de A\u03b2 1-42 no LCR diminui em cerca de 50%. Ao mesmo tempo, as concentra\u00e7\u00f5es de tau e pTau181 no LCR aumentam at\u00e9 200\u2013300% dos valores normais [17].<\/p>\n\n\n\n<p>Em laborat\u00f3rios certificados, A\u03b21-42, Tau e pTau181 s\u00e3o determinados simultaneamente como padr\u00e3o. [26] A determina\u00e7\u00e3o adicional de A\u03b21-40 permite utilizar o r\u00e1cio A\u03b21-42\/A\u03b21-40 para compensar as flutua\u00e7\u00f5es inter-individuais na produ\u00e7\u00e3o de amiloide e reduzir a suscetibilidade a desvios pr\u00e9-anal\u00edticos.<\/p>\n\n\n\n<p>Estes marcadores do LCR s\u00e3o atualmente considerados como os melhores biomarcadores validados da DA. Atingem um elevado n\u00edvel de exatid\u00e3o diagn\u00f3stica, melhoram o diagn\u00f3stico diferencial e podem fornecer informa\u00e7\u00f5es sobre a gravidade da neurodegenera\u00e7\u00e3o e o progn\u00f3stico cl\u00ednico [17,43]. Por conseguinte, contribuem significativamente para a certeza do diagn\u00f3stico, para evitar outras etapas de diagn\u00f3stico desnecess\u00e1rias e para a tomada de decis\u00f5es relativas ao tratamento e aos cuidados [12,35].<\/p>\n\n\n\n<p>A an\u00e1lise dos marcadores do LCR \u00e9 atualmente a \u00fanica abordagem dispon\u00edvel na pr\u00e1tica que pode fornecer simultaneamente provas da patologia amiloide cerebral, bem como provas da morte das c\u00e9lulas neuronais e da hiperfosforila\u00e7\u00e3o da tau. No entanto, tamb\u00e9m s\u00e3o poss\u00edveis resultados lim\u00edtrofes, contradit\u00f3rios ou falsos positivos e falsos negativos [17,28,38]. Al\u00e9m disso, esta abordagem n\u00e3o permite fazer qualquer afirma\u00e7\u00e3o sobre as limita\u00e7\u00f5es funcionais do c\u00e9rebro e a extens\u00e3o da patologia em cada uma das regi\u00f5es cerebrais. Por conseguinte, em casos clinicamente at\u00edpicos ou pouco claros, um exame como o FDG-PET pode ser utilizado para o diagn\u00f3stico diferencial, em primeiro lugar ou em complemento do diagn\u00f3stico do LCR [25,29].<\/p>\n\n\n\n<p>Outras causas, como a encefalite, podem tamb\u00e9m ser exclu\u00eddas ou reconhecidas no l\u00edquido cefalorraquidiano ao mesmo tempo que a patologia da doen\u00e7a de Alzheimer \u00e9 detectada. Uma concentra\u00e7\u00e3o de tau significativamente aumentada com A\u03b21-42 normal e sem pTau ou com um aumento relativamente ligeiro \u00e9 uma constela\u00e7\u00e3o t\u00edpica da doen\u00e7a de Creutzfeldt-Jakob (DCJ). Se houver suspeita de doen\u00e7a de Creutzfeld-Jakob (DCJ), podem tamb\u00e9m ser determinados outros marcadores. Por exemplo, a dete\u00e7\u00e3o da prote\u00edna 14-3-3 no l\u00edquido cefalorraquidiano pode indicar uma morte celular neuronal r\u00e1pida e \u00e9 um marcador altamente sens\u00edvel, embora n\u00e3o espec\u00edfico, da DCJ. O mais recente m\u00e9todo RT-QuIC pode detetar a prote\u00edna pri\u00f3nica patol\u00f3gica e tem uma especificidade significativamente mais elevada com uma sensibilidade compar\u00e1vel [21].<\/p>\n\n\n\n<h3 id=\"indicacoes-para-a-puncao-lombar-diagnostica\" class=\"wp-block-heading\">Indica\u00e7\u00f5es para a pun\u00e7\u00e3o lombar diagn\u00f3stica<\/h3>\n\n\n\n<p>As principais indica\u00e7\u00f5es para um exame do LCR como parte de um diagn\u00f3stico adicional s\u00e3o<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Primeiros sintomas antes dos 65 anos de idade<\/li>\n\n\n\n<li>Deteriora\u00e7\u00e3o cognitiva rapidamente progressiva (por exemplo, suspeita de doen\u00e7a de Creutzfeld-Jakob)  <\/li>\n\n\n\n<li>Apresenta\u00e7\u00e3o cl\u00ednica at\u00edpica  <\/li>\n\n\n\n<li>Exclus\u00e3o de doen\u00e7as inflamat\u00f3rias do SNC  <\/li>\n\n\n\n<li>Suspeita de fase inicial da doen\u00e7a de Alzheimer (incluindo MCI) de acordo com indica\u00e7\u00e3o individualizada<\/li>\n\n\n\n<li>Pun\u00e7\u00e3o descompressiva diagn\u00f3stica por suspeita de hidrocefalia de press\u00e3o normal.<\/li>\n<\/ul>\n\n\n\n<p>A indica\u00e7\u00e3o para a pun\u00e7\u00e3o lombar (PL) deve ser sempre determinada ap\u00f3s uma avalia\u00e7\u00e3o cuidadosa dos riscos e benef\u00edcios. Devem ser tidas em conta as poss\u00edveis contra-indica\u00e7\u00f5es, os aspectos m\u00e9dico-biol\u00f3gicos, biogr\u00e1ficos, psicol\u00f3gicos e pr\u00e1ticos, bem como as prefer\u00eancias do doente. [38] \u00c9 obrigat\u00f3ria uma informa\u00e7\u00e3o adequada sobre o procedimento e os riscos, bem como sobre os benef\u00edcios esperados do exame e as alternativas poss\u00edveis.    <\/p>\n\n\n\n<p>Na Su\u00ed\u00e7a, o seguro de sa\u00fade obrigat\u00f3rio (OKP) cobre, desde 1 de julho de 2019, os custos das an\u00e1lises dos marcadores do LCR, incluindo para os doentes com CCL, sob reserva de certas limita\u00e7\u00f5es.<\/p>\n\n\n\n<h3 id=\"realizacao\" class=\"wp-block-heading\">Realiza\u00e7\u00e3o<\/h3>\n\n\n\n<p>A pun\u00e7\u00e3o lombar diagn\u00f3stica pode ser efectuada por rotina em ambulat\u00f3rio, \u00e9 de baixo risco se forem observadas contra-indica\u00e7\u00f5es e \u00e9 geralmente bem tolerada [16,39,49]. Para al\u00e9m da informa\u00e7\u00e3o escrita sobre o procedimento e os riscos da pun\u00e7\u00e3o lombar, deve ser realizada previamente uma discuss\u00e3o explicativa sobre os poss\u00edveis resultados dos biomarcadores e quaisquer perspectivas e op\u00e7\u00f5es de tratamento associadas [19,38].<\/p>\n\n\n\n<p>O manuseamento pr\u00e9-anal\u00edtico exato das amostras de LCR para a determina\u00e7\u00e3o de rotina dos marcadores do LCR est\u00e1 descrito nas orienta\u00e7\u00f5es internacionais [27]. A amostra de LCR \u00e9 colhida por gotejamento e os primeiros 1-2 ml s\u00e3o eliminados. A amostra deve ser colhida diretamente para um tubo com propriedades de baixa liga\u00e7\u00e3o \u00e0s prote\u00ednas, por exemplo, de polipropileno, para evitar que a prote\u00edna amiloide, em particular, se fixe na parede do tubo, conduzindo assim a resultados falsos [13]. Idealmente, as amostras devem ser transportadas para o laborat\u00f3rio refrigeradas ou congeladas, mas tamb\u00e9m podem ser transportadas \u00e0 temperatura ambiente se o tempo de viagem for curto. Em geral, devem ser seguidas as instru\u00e7\u00f5es e especifica\u00e7\u00f5es do laborat\u00f3rio de determina\u00e7\u00e3o.<\/p>\n\n\n\n<p>A interpreta\u00e7\u00e3o dos resultados baseia-se em intervalos de refer\u00eancia espec\u00edficos do laborat\u00f3rio, pelo que se limita inicialmente \u00e0 presen\u00e7a ou aus\u00eancia das patologias cerebrais correspondentes. Mesmo no caso de achados laboratoriais quimicamente claros de marcadores do LCR, estes n\u00e3o devem ser automaticamente equiparados ao diagn\u00f3stico e requerem uma avalia\u00e7\u00e3o adicional em rela\u00e7\u00e3o ao contexto cl\u00ednico global [5]. <\/p>\n\n\n\n<h3 id=\"notificacao-dos-resultados\" class=\"wp-block-heading\">Notifica\u00e7\u00e3o dos resultados<\/h3>\n\n\n\n<p>Os biomarcadores do LCR fazem atualmente parte dos crit\u00e9rios de diagn\u00f3stico internacionais e tornaram-se recentemente cada vez mais importantes no diagn\u00f3stico da dem\u00eancia neste pa\u00eds [14]. No entanto, s\u00e3o apenas uma parte do processo de diagn\u00f3stico [9,38]. Os biomarcadores devem ser sempre avaliados no contexto dos resultados da hist\u00f3ria cl\u00ednica, do exame cl\u00ednico e neuropsicol\u00f3gico e de outros exames complementares. A interpreta\u00e7\u00e3o e a comunica\u00e7\u00e3o de resultados lim\u00edtrofes ou contradit\u00f3rios podem constituir um desafio particular. A avalia\u00e7\u00e3o e a categoriza\u00e7\u00e3o devem ser efectuadas no \u00e2mbito de conselhos multidisciplinares ou de confer\u00eancias de diagn\u00f3stico, como geralmente recomendado pelas Cl\u00ednicas Su\u00ed\u00e7as da Mem\u00f3ria [9,38].<\/p>\n\n\n\n<p>Em princ\u00edpio, as pessoas afectadas t\u00eam o direito de conhecer os resultados das suas investiga\u00e7\u00f5es m\u00e9dicas [45]. No entanto, no caso de dados sens\u00edveis ou de dif\u00edcil compreens\u00e3o, cabe \u00e0 pessoa que presta o tratamento comunicar os resultados de forma compreens\u00edvel e inseri-los num conceito global de diagn\u00f3stico e terap\u00eautica.<\/p>\n\n\n\n<p>A comunica\u00e7\u00e3o cuidadosa e emp\u00e1tica de um diagn\u00f3stico confirmado e grave \u00e9 um grande desafio e requer muita experi\u00eancia e profissionalismo [6]. Em determinadas circunst\u00e2ncias, o diagn\u00f3stico expl\u00edcito pode trazer um certo al\u00edvio \u00e0s pessoas afectadas, uma vez que existe agora uma explica\u00e7\u00e3o reconhec\u00edvel para os problemas que enfrentam. Por outro lado, existe o risco de a revela\u00e7\u00e3o poder desencadear reac\u00e7\u00f5es psicol\u00f3gicas negativas nas pessoas afectadas, tais como medo, tristeza, raiva, preocupa\u00e7\u00e3o com a estigmatiza\u00e7\u00e3o ou mesmo pensamentos suicidas [6]. No entanto, com uma abordagem adequada, o risco de uma rea\u00e7\u00e3o negativa persistente \u00e9 globalmente baixo e os aspectos positivos ultrapassam claramente os negativos [10,48]. As diretrizes internacionais e as normas de qualidade su\u00ed\u00e7as em mat\u00e9ria de diagn\u00f3stico de dem\u00eancia recomendam que os resultados sejam comunicados em conformidade [9].<\/p>\n\n\n\n<h3 id=\"mudanca-de-paradigma-no-diagnostico-da-doenca-de-alzheimer-a-importancia-do-diagnostico-precoce\" class=\"wp-block-heading\">Mudan\u00e7a de paradigma no diagn\u00f3stico da doen\u00e7a de Alzheimer: a import\u00e2ncia do diagn\u00f3stico precoce<\/h3>\n\n\n\n<p>A valida\u00e7\u00e3o e a utiliza\u00e7\u00e3o crescente de biomarcadores de patologias cerebrais permitiram o desenvolvimento de novos crit\u00e9rios para a DA, que est\u00e3o a ser cada vez mais utilizados na pr\u00e1tica cl\u00ednica [2,3,14]. Contrariamente ao anterior diagn\u00f3stico de exclus\u00e3o da doen\u00e7a de Alzheimer, estes novos crit\u00e9rios atribuem aos biomarcadores um importante papel de apoio ao diagn\u00f3stico e, com resultados adequados dos biomarcadores, permitem confirmar os sintomas da patologia cerebral da doen\u00e7a de Alzheimer. Al\u00e9m disso, os novos crit\u00e9rios t\u00eam em conta o facto de o desenvolvimento da patologia preceder em muitos anos os est\u00e1dios de dem\u00eancia e de a doen\u00e7a progredir clinicamente de est\u00e1dios assintom\u00e1ticos, passando por um d\u00e9fice cognitivo ligeiro, at\u00e9 aos est\u00e1dios de dem\u00eancia [24]. O diagn\u00f3stico formal ou a exclus\u00e3o da doen\u00e7a \u00e9, por conseguinte, poss\u00edvel numa fase precoce da evolu\u00e7\u00e3o cl\u00ednica da doen\u00e7a, ou seja, logo na fase de d\u00e9fice cognitivo ligeiro [3]. Um diagn\u00f3stico precoce e preciso da doen\u00e7a de Alzheimer n\u00e3o s\u00f3 permite uma interven\u00e7\u00e3o precoce, como tamb\u00e9m oferece a oportunidade de prever melhor a evolu\u00e7\u00e3o da doen\u00e7a e desenvolver estrat\u00e9gias de tratamento individualizadas. O diagn\u00f3stico numa fase precoce pode tamb\u00e9m ajudar a retardar o decl\u00ednio cognitivo, a tratar adequadamente os sintomas neuropsiqui\u00e1tricos associados e a melhorar a qualidade de vida dos doentes e dos seus familiares atrav\u00e9s de uma interven\u00e7\u00e3o precoce. O diagn\u00f3stico precoce \u00e9 particularmente importante no contexto do desenvolvimento de novas terapias, como as imunoterapias anti-amiloide, de modo a poder intervir nos processos patol\u00f3gicos o mais cedo poss\u00edvel.<\/p>\n\n\n\n<h3 id=\"perspectivas\" class=\"wp-block-heading\">Perspectivas<\/h3>\n\n\n\n<p><strong>Biomarcadores sangu\u00edneos: <\/strong>Embora os marcadores A\u03b21-42, tau e pTau181 do LCR, bem como A\u03b21-42\/A\u03b21-40, sejam considerados amplamente estabelecidos em termos do seu valor diagn\u00f3stico, est\u00e3o atualmente a ser investigados novos candidatos a biomarcadores. Para al\u00e9m do diagn\u00f3stico preciso da patologia da doen\u00e7a de Alzheimer, estes marcadores devem tamb\u00e9m mapear, na medida do poss\u00edvel, processos patol\u00f3gicos adicionais, permitindo assim uma declara\u00e7\u00e3o de diagn\u00f3stico e progn\u00f3stico mais precisa.   <\/p>\n\n\n\n<p>Os biomarcadores sangu\u00edneos tornaram-se cada vez mais importantes nos \u00faltimos anos, apesar de ainda n\u00e3o estarem autorizados para a pr\u00e1tica cl\u00ednica na Europa ou na Su\u00ed\u00e7a a partir de 2024. Representar\u00e3o uma alternativa n\u00e3o invasiva e econ\u00f3mica \u00e0 an\u00e1lise do l\u00edquido cefalorraquidiano ou \u00e0 imagiologia PET e poder\u00e3o vir a ter uma aplica\u00e7\u00e3o mais ampla no diagn\u00f3stico de rotina. Os biomarcadores sangu\u00edneos mais promissores atualmente dispon\u00edveis incluem [34].<\/p>\n\n\n\n<p><strong>Cadeias leves de neurofilamentos (NfL):<\/strong> A NfL (neurofilament light chain, NfL) \u00e9 um dos novos biomarcadores mais bem estudados. A NfL \u00e9 libertada dos neur\u00f3nios em caso de les\u00e3o axonal, independentemente da causa, e est\u00e1 associada \u00e0 gravidade dos sintomas em v\u00e1rias doen\u00e7as neurodegenerativas [1]. A NfL pode ser medida tanto no LCR como no sangue e, portanto, tem o potencial de mapear o desenvolvimento de processos cerebrais com danos neuronais ao longo do tempo (Ashton et al., 2021; Mattsson et al., 2017). No entanto, devido \u00e0 falta de especificidade da doen\u00e7a, o NfL n\u00e3o \u00e9 muito adequado para o diagn\u00f3stico diferencial da doen\u00e7a de Alzheimer [11].<\/p>\n\n\n\n<p><strong>Prote\u00ednas tau fosforiladas (pTau): <\/strong>As pTau181, pTau217 e pTau231 plasm\u00e1ticas est\u00e3o entre os biomarcadores sangu\u00edneos mais promissores para a patologia da DA. Em v\u00e1rios estudos, estas prote\u00ednas foram estreitamente associadas a patologias cerebrais de tau e amiloide e foram capazes de distinguir a DA de outras doen\u00e7as neurodegenerativas [11,32,46]. A sua especificidade e sensibilidade diagn\u00f3sticas foram tamb\u00e9m compar\u00e1veis \u00e0s dos marcadores do LCR [7]. Em doentes com d\u00e9fice cognitivo ligeiro, a pTau, por si s\u00f3 ou em conjunto com par\u00e2metros dispon\u00edveis, como a idade e os resultados de testes cognitivos, pode ajudar a identificar a patologia cerebral da doen\u00e7a de Alzheimer e a prever com elevada precis\u00e3o a futura deteriora\u00e7\u00e3o cognitiva  [11,33].<\/p>\n\n\n\n<p><strong>Amiloide 42\/40: <\/strong>O A\u03b242\/40 plasm\u00e1tico est\u00e1 reduzido na presen\u00e7a de patologia amiloide cerebral, embora num grau relativamente baixo. Este facto limita o valor diagn\u00f3stico das medi\u00e7\u00f5es de amiloide no sangue atualmente dispon\u00edveis e torna-as menos adequadas do que a pTau para reconhecer com fiabilidade a patologia amiloide.   <\/p>\n\n\n\n<p><strong>Prote\u00edna glial fibrilar \u00e1cida (GFAP):<\/strong> A GFAP \u00e9 o principal componente dos filamentos interm\u00e9dios dos astr\u00f3citos no SNC, sendo por isso considerada um marcador de astrocitose e de ativa\u00e7\u00e3o da astroglia. Pode ser medida tanto no l\u00edquido cefalorraquidiano como no sangue. V\u00e1rios estudos demonstraram que o GFAP medido no sangue, em particular, tem boas propriedades de diagn\u00f3stico, de diagn\u00f3stico diferencial e de previs\u00e3o da doen\u00e7a de Alzheimer [50].<\/p>\n\n\n\n<p>Os novos candidatos a biomarcadores devem ser validados em mais estudos independentes antes de poderem ser utilizados na pr\u00e1tica cl\u00ednica de rotina. [33] Para garantir uma implementa\u00e7\u00e3o e disponibilidade generalizadas, muitos dos novos m\u00e9todos de determina\u00e7\u00e3o ter\u00e3o tamb\u00e9m de ser simplificados e o tratamento pr\u00e9-anal\u00edtico das amostras ter\u00e1 de ser normalizado. A utiliza\u00e7\u00e3o cl\u00ednica dos novos biomarcadores sangu\u00edneos poderia, por exemplo, melhorar a via de diagn\u00f3stico em termos de custos e de rapidez, aplicando um processo em duas fases recentemente proposto [18]. Em caso de suspeita cl\u00ednica de doen\u00e7a de Alzheimer, come\u00e7am por ser medidos biomarcadores sangu\u00edneos como o pTau217. Se o resultado for claramente positivo ou claramente negativo, pode prescindir-se de outros testes adicionais invasivos (pun\u00e7\u00e3o lombar) ou dispendiosos (PET amiloide) devido \u00e0 especificidade e sensibilidade muito elevadas (&gt;95%). S\u00f3 seriam necess\u00e1rias investiga\u00e7\u00f5es adicionais em casos com resultados pouco claros ou lim\u00edtrofes. Num estudo publicado recentemente, foi demonstrado que, com esta abordagem, os resultados dos marcadores sangu\u00edneos permaneciam pouco claros em apenas cerca de 20% dos casos e exigiam diagn\u00f3sticos adicionais [8]. Atualmente, prossegue a investiga\u00e7\u00e3o sobre marcadores sangu\u00edneos melhorados para utiliza\u00e7\u00e3o cl\u00ednica, estando j\u00e1 dispon\u00edveis para investiga\u00e7\u00e3o v\u00e1rios m\u00e9todos com resultados muito promissores [23]. Prev\u00ea-se que os biomarcadores sangu\u00edneos estejam dispon\u00edveis para utiliza\u00e7\u00e3o cl\u00ednica dentro de alguns anos.<\/p>\n\n\n\n<p>A disponibilidade de biomarcadores sangu\u00edneos n\u00e3o invasivos e rent\u00e1veis n\u00e3o s\u00f3 facilitar\u00e1 a investiga\u00e7\u00e3o de novas abordagens preventivas e terap\u00eauticas nas fases muito precoces das doen\u00e7as neurodegenerativas, como tamb\u00e9m \u00e9 suscet\u00edvel de provocar altera\u00e7\u00f5es significativas no diagn\u00f3stico e no tratamento das perturba\u00e7\u00f5es cognitivas na velhice. Apesar da disponibilidade mais f\u00e1cil e da melhoria do valor diagn\u00f3stico e progn\u00f3stico dos biomarcadores, peritos experientes, por exemplo em cl\u00ednicas especializadas em mem\u00f3ria, devem continuar a determinar a indica\u00e7\u00e3o, a interpretar os resultados e a fazer recomenda\u00e7\u00f5es com base neles no futuro. <\/p>\n\n\n\n<h3 id=\"biomarcadores-de-sintomas-neuropsiquiatricos\" class=\"wp-block-heading\">Biomarcadores de sintomas neuropsiqui\u00e1tricos<\/h3>\n\n\n\n<p>Os sintomas neuropsiqui\u00e1tricos (NPS), como a depress\u00e3o, a apatia, a agressividade ou as perturba\u00e7\u00f5es do sono, ocorrem muito frequentemente no contexto da dem\u00eancia (at\u00e9 98% dos casos) e prejudicam significativamente a qualidade de vida dos doentes e dos seus familiares [15,36]. Ocorrem frequentemente no in\u00edcio ou mesmo antes do aparecimento de perturba\u00e7\u00f5es cognitivas, raz\u00e3o pela qual desempenham tamb\u00e9m um papel importante na fase inicial da doen\u00e7a de Alzheimer [22,44]. Al\u00e9m disso, a presen\u00e7a destes sintomas est\u00e1 associada a um pior progn\u00f3stico em termos de decl\u00ednio cognitivo mais r\u00e1pido e de institucionaliza\u00e7\u00e3o mais precoce [41]. Por estas raz\u00f5es, \u00e9 importante validar biomarcadores tamb\u00e9m para estes sintomas e inclu\u00ed-los no diagn\u00f3stico, tratamento e progn\u00f3stico. Estudos iniciais mostram que biomarcadores individuais, como o GFAP e outras prote\u00ednas do plasma sangu\u00edneo, podem facilitar a previs\u00e3o de NPS persistentes durante um per\u00edodo de tempo mais longo [40,42]. No futuro, esses marcadores poder\u00e3o facilitar significativamente a tomada de decis\u00f5es personalizadas para o tratamento do SPN e, assim, ter potencialmente tamb\u00e9m uma influ\u00eancia positiva no curso da doen\u00e7a e na qualidade de vida.<\/p>\n\n\n\n<h3 id=\"resumo\" class=\"wp-block-heading\">Resumo<\/h3>\n\n\n\n<p>Os marcadores do LCR atualmente dispon\u00edveis e bem estabelecidos permitem um diagn\u00f3stico mais preciso e precoce da DA e fornecem informa\u00e7\u00f5es valiosas sobre a presen\u00e7a de outras causas de perturba\u00e7\u00f5es neurocognitivas e neuropsiqui\u00e1tricas. Fazem agora parte do diagn\u00f3stico alargado na Su\u00ed\u00e7a, que \u00e9 normalmente efectuado em <em>cl\u00ednicas de mem\u00f3ria<\/em> ou por peritos especializados. Os marcadores do LCR s\u00e3o particularmente importantes nas fases iniciais do desenvolvimento de perturba\u00e7\u00f5es cognitivas e em doentes relativamente jovens, quando um diagn\u00f3stico etiol\u00f3gico suficientemente preciso \u00e9 essencial para um tratamento espec\u00edfico e para o planeamento da vida futura. No entanto, os biomarcadores tamb\u00e9m devem ser geralmente considerados como uma op\u00e7\u00e3o de diagn\u00f3stico e oferecidos aos doentes como parte da avalia\u00e7\u00e3o, se a rela\u00e7\u00e3o risco-benef\u00edcio for suficientemente favor\u00e1vel.     <\/p>\n\n\n\n<p>Num futuro pr\u00f3ximo, espera-se que os biomarcadores sangu\u00edneos estejam dispon\u00edveis como uma alternativa rent\u00e1vel e n\u00e3o invasiva, conduzindo assim a uma utiliza\u00e7\u00e3o muito mais alargada dos biomarcadores. No entanto, no futuro, os biomarcadores tamb\u00e9m ter\u00e3o de ser avaliados no contexto geral dos exames anamn\u00e9sicos, cl\u00ednicos e outros exames adicionais dispon\u00edveis. Os peritos e os centros especializados<em> (cl\u00ednicas de mem\u00f3ria) <\/em>devem continuar a interpretar e a comunicar os resultados e a fornecer o tratamento e o aconselhamento necess\u00e1rios.  <\/p>\n\n\n\n<p><strong>Mensagens para levar para casa<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Apesar da frequ\u00eancia e da import\u00e2ncia da doen\u00e7a de Alzheimer, em muitos casos esta n\u00e3o \u00e9 diagnosticada ou s\u00f3 \u00e9 diagnosticada numa fase avan\u00e7ada da doen\u00e7a, o que limita consideravelmente as op\u00e7\u00f5es de tratamento.<\/li>\n\n\n\n<li>Os marcadores moleculares do LCR, como a amiloide beta 1-42 (A\u03b21-42), a tau total (tau) e a tau fosforilada (pTau181), ou as t\u00e9cnicas de imagiologia, como a PET amiloide, s\u00e3o considerados m\u00e9todos de diagn\u00f3stico fi\u00e1veis que permitem a dete\u00e7\u00e3o precoce da patologia central da doen\u00e7a de Alzheimer.<\/li>\n\n\n\n<li>Num futuro pr\u00f3ximo, os biomarcadores baseados no sangue poder\u00e3o tornar-se cada vez mais importantes e facilitar muito o diagn\u00f3stico, uma vez que representam uma alternativa facilmente acess\u00edvel e mais econ\u00f3mica.<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p>Literatura:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Al Shweiki MR, Steinacker P, Oeckl P, et al.: Neurofilament light chain as a blood biomarker to differentiate psychiatric disorders from behavioural variant frontotemporal dementia. J Psychiatr Res 2019; 113: 137\u2013140. <br><a href=\"https:\/\/doi.org\/10.1016\/j.jpsychires.2019.03.019\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1016\/j.jpsychires.2019.03.019<\/a>.<\/li>\n\n\n\n<li>Albert MS, DeKosky ST, Dickson D, et al.: The diagnosis of mild cognitive impairment due to Alzheimer\u2019s disease: recommendations from the National Institute on Aging-Alzheimer\u2019s Association workgroups on diagnostic guidelines for Alzheimer\u2019s disease. Alzheimers Dement 2011; 7(3): 270\u2013279.<br><a href=\"https:\/\/doi.org\/10.1016\/j.jalz.2011.03.008\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1016\/j.jalz.2011.03.008<\/a>. <\/li>\n\n\n\n<li>American Psychiatric Association: Diagnostic and statistical manual of mental disorders: DSM-5. 5<sup>th<\/sup> ed. In. Washington, D.C.: American Psychiatric Publishing 2013.  <\/li>\n\n\n\n<li>Ashton, NJ, Janelidze S, Al Khleifat A, et al.: A multicentre validation study of the diagnostic value of plasma neurofilament light. Nat Commun 2021; 12(1): 3400. <a href=\"https:\/\/doi.org\/10.1038\/s41467-021-23620-z\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1038\/s41467-021-23620-z<\/a>. <\/li>\n\n\n\n<li>Baldeiras I, Santana I, Leit\u00e3o MJ, et al.: Erlangen Score as a tool to predict progression from mild cognitive impairment to dementia in Alzheimer\u2019s disease. Alzheimers Res Ther 2019; 11(1): 2. <a href=\"https:\/\/doi.org\/10.1186\/s13195-018-0456-x\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1186\/s13195-018-0456-x<\/a>. <\/li>\n\n\n\n<li>Bamford C, Lamont S, Eccles M, et al.: Disclosing a diagnosis of dementia: a systematic review. Int J Geriatr Psychiatry 2004; 19(2): 151\u2013169. <a href=\"https:\/\/doi.org\/10.1002\/gps.1050\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1002\/gps.1050<\/a>. <\/li>\n\n\n\n<li>Barth\u00e9lemy NR, Salvad\u00f3 G, Schindler SE, et al.: Highly accurate blood test for Alzheimer\u2019s disease is similar or superior to clinical cerebrospinal fluid tests. Nat Med 2024; 30(4): 1085\u20131095. <a href=\"https:\/\/doi.org\/10.1038\/s41591-024-02869-z\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1038\/s41591-024-02869-z<\/a>. <\/li>\n\n\n\n<li>Brum WS, Cullen NC, Janelidze S, et al.: A two-step workflow based on plasma p-tau217 to screen for amyloid \u03b2 positivity with further confirmatory testing only in uncertain cases. Nat Aging 2023; 3(9): 1079\u20131090. <a href=\"https:\/\/doi.org\/10.1038\/s43587-023-00471-5\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1038\/s43587-023-00471-5<\/a>. <\/li>\n\n\n\n<li>B\u00fcrge M, Bieri G, Br\u00fchlmeier M, et al.:. [Recommendations of Swiss Memory Clinics for the Diagnosis of Dementia]. Praxis 2018 (Bern 1994), 107(8), 435\u2013451. <a href=\"https:\/\/doi.org\/10.1024\/1661-8157\/a002948\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1024\/1661-8157\/a002948<\/a>.  <\/li>\n\n\n\n<li>Carpenter BD, Xiong C, Porensky EK, et al.: Reaction to a dementia diagnosis in individuals with Alzheimer\u2019s disease and mild cognitive impairment. J Am Geriatr Soc 2018; 56(3): 405\u2013412. <a href=\"https:\/\/doi.org\/10.1111\/j.1532-5415.2007.01600.x\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1111\/j.1532-5415.2007.01600.x<\/a>. <\/li>\n\n\n\n<li>Clark C, Lewczuk P, Kornhuber J, et al.: Plasma neurofilament light and phosphorylated tau 181 as biomarkers of Alzheimer\u2019s disease pathology and clinical disease progression. Alzheimers Res Ther 2021; 13(1): 65. <a href=\"https:\/\/doi.org\/10.1186\/s13195-021-00805-8\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1186\/s13195-021-00805-8<\/a>. <\/li>\n\n\n\n<li>Cognat E, Mouton Liger F, Troussi\u00e8re AC, et al.: What is the clinical impact of cerebrospinal fluid biomarkers on final diagnosis and management in patients with mild cognitive impairment in clinical practice? Results from a nation-wide prospective survey in France. BMJ Open 2019; 9(5): e026380. <a href=\"https:\/\/doi.org\/10.1136\/bmjopen-2018-026380\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1136\/bmjopen-2018-026380<\/a>. <\/li>\n\n\n\n<li>Dubois B, Feldman HH, Jacova C et al.: Advancing research diagnostic criteria for Alzheimer\u2019s disease: the IWG-2 criteria. Lancet Neurol 2014; 13(6): 614\u2013629. <a href=\"https:\/\/doi.org\/10.1016\/S1474-4422(14)70090-0\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1016\/S1474-4422(14)70090-0<\/a>.<\/li>\n\n\n\n<li>Dubois B, Villain N, Frisoni GB, et al.: Clinical diagnosis of Alzheimer\u2019s disease: recommendations of the International Working Group. Lancet Neurol 2021; 20(6): 484\u2013496. <a href=\"https:\/\/doi.org\/10.1016\/S1474-4422(21)00066-1\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1016\/S1474-4422(21)00066-1<\/a> <\/li>\n\n\n\n<li>Eikelboom WS, van den Berg E, Singleton EH, et al.: Neuropsychiatric and Cognitive Symptoms Across the Alzheimer Disease Clinical Spectrum: Cross-sectional and Longitudinal Associations. Neurology 2021; 97(13): e1276\u2013e1287. <a href=\"https:\/\/doi.org\/10.1212\/wnl.0000000000012598\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1212\/wnl.0000000000012598<\/a>. <\/li>\n\n\n\n<li>Engelborghs S, Niemantsverdriet E, Struyfs H, et al.: Consensus guidelines for lumbar puncture in patients with neurological diseases. Alzheimers Dement (Amst) 2017; 8: 111\u2013126. <a href=\"https:\/\/doi.org\/10.1016\/j.dadm.2017.04.007\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1016\/j.dadm.2017.04.007<\/a>. <\/li>\n\n\n\n<li>Hansson O: Biomarkers for neurodegenerative diseases. Nat Med 2021; 27(6): 954\u2013963. <a href=\"https:\/\/doi.org\/10.1038\/s41591-021-01382-x\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1038\/s41591-021-01382-x<\/a>.  <\/li>\n\n\n\n<li>Hansson O, Blennow K, Zetterberg H, Dage J: Blood biomarkers for Alzheimer\u2019s disease in clinical practice and trials. Nat Aging 2023; 3(5): 506\u2013519. <a href=\"https:\/\/doi.org\/10.1038\/s43587-023-00403-3\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1038\/s43587-023-00403-3<\/a>.  <\/li>\n\n\n\n<li>Hansson O, Edelmayer RM, Boxer AL, et al.: The Alzheimer\u2019s Association appropriate use recommendations for blood biomarkers in Alzheimer\u2019s disease. Alzheimers Dement 2022; 18(12): 2669\u20132686. <a href=\"https:\/\/doi.org\/10.1002\/alz.12756\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1002\/alz.12756<\/a>. <\/li>\n\n\n\n<li>Hemmeter U, Strnad J, Decrey-Wick H, et al. (2021): Weiterentwicklung von Empfehlungen in den Bereichen Fr\u00fcherkennung, Diagnostik und Behandlung f\u00fcr die Grundversorgung. Retrieved 25.09.2024 from <a href=\"http:\/\/www.bag.admin.ch\/dam\/bag\/de\/dokumente\/nat-gesundheitsstrategien\/nationale-demenzstrategie\/hf-qualitaet\/6_1_grundversorgung\/Empfehlungen_Grundversorgung%20.pdf.download.pdf\/Empfehlungen%20in%20den%20Bereichen%20Fr\u00fcherkennung,%20Diagnostik%20und%20Behandlung%20f\u00fcr%20die%20Grundversorgung.pdf\" target=\"_blank\" rel=\"noopener\">www.bag.admin.ch\/dam\/bag\/de\/dokumente\/nat-gesundheitsstrategien\/nationale-demenzstrategie\/hf-qualitaet\/6_1_grundversorgung\/Empfehlungen_Grundversorgung%20.pdf.download.pdf\/Empfehlungen%20in%20den%20Bereichen%20Fr\u00fcherkennung,%20Diagnostik%20und%20Behandlung%20f\u00fcr%20die%20Grundversorgung.pdf<\/a><\/li>\n\n\n\n<li>Hermann P, Appleby B, Brandel JP, et al.: Biomarkers and diagnostic guidelines for sporadic Creutzfeldt-Jakob disease. Lancet Neurol 2021; 20(3): 235\u2013246. <a href=\"https:\/\/doi.org\/10.1016\/S1474-4422(20)30477-4\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1016\/S1474-4422(20)30477-4<\/a>. <\/li>\n\n\n\n<li>Ismail Z, Smith EE, Geda Y, et al.: Neuropsychiatric symptoms as early manifestations of emergent dementia: Provisional diagnostic criteria for mild behavioral impairment. Alzheimers Dement 2016; 12(2): 195\u2013202. <a href=\"https:\/\/doi.org\/10.1016\/j.jalz.2015.05.017\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1016\/j.jalz.2015.05.017<\/a>. <\/li>\n\n\n\n<li>Janelidze S, Bali D, Ashton NJ, et al.: Head-to-head comparison of 10 plasma phospho-tau assays in prodromal Alzheimer\u2019s disease. Brain 2023; 146(4): 1592\u20131601. <a href=\"https:\/\/doi.org\/10.1093\/brain\/awac333\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1093\/brain\/awac333<\/a>. <\/li>\n\n\n\n<li>Jansen WJ, Ossenkoppele R, Knol DL, et al.: Prevalence of cerebral amyloid pathology in persons without dementia: a meta-analysis. JAMA 2015; 313(19): 1924\u20131938. <a href=\"https:\/\/doi.org\/10.1001\/jama.2015.4668\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1001\/jama.2015.4668<\/a>. <\/li>\n\n\n\n<li>Juengling FD, Allenbach G, Bruehlmeier M, et al.: Appropriate use criteria for dementia amyloid imaging in Switzerland \u2013 mini-review and statement on behalf of the Swiss Society of Nuclear Medicine and the Swiss Memory Clinics. Nuklearmedizin 2021; 60(1): 7\u20139. <a href=\"https:\/\/doi.org\/10.1055\/a-1277-6014\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1055\/a-1277-6014<\/a>. <\/li>\n\n\n\n<li>Karlsson L, Vogel J, Arvidsson I, et al.: Cerebrospinal fluid reference proteins increase accuracy and interpretability of biomarkers for brain diseases. Nat Commun 2024; 15(1): 3676. <a href=\"https:\/\/doi.org\/10.1038\/s41467-024-47971-5\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1038\/s41467-024-47971-5<\/a>. <\/li>\n\n\n\n<li>Lewczuk P, Beck G, Esselmann H, et al.: Effect of sample collection tubes on cerebrospinal fluid concentrations of tau proteins and amyloid beta peptides. Clin Chem 2006; 52(2): 332\u2013334. <a href=\"https:\/\/doi.org\/10.1373\/clinchem.2005.058776\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1373\/clinchem.2005.058776<\/a>. <\/li>\n\n\n\n<li>Magnin E, Popp J: [Cerebrospinal fluid biomarkers of Alzheimer\u2019s disease in current clinical practice]. Rev Med Suisse 2016; 12(515): 791\u2013794.  <\/li>\n\n\n\n<li>Massa F, Farotti L, Eusebi P, et al.: Reciprocal Incremental Value of 18F-FDG-PET and Cerebrospinal Fluid Biomarkers in Mild Cognitive Impairment Patients Suspected for Alzheimer\u2019s Disease and Inconclusive First Biomarker. J Alzheimers Dis 2019; 72(4): 1193\u20131207. <a href=\"https:\/\/doi.org\/10.3233\/JAD-190539\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.3233\/JAD-190539<\/a>. <\/li>\n\n\n\n<li>Mattsson N, Andreasson U, Zetterberg H, et al.: Association of Plasma Neurofilament Light With Neurodegeneration in Patients With Alzheimer Disease. JAMA Neurol 2017; 74(5): 557\u2013566. <a href=\"https:\/\/doi.org\/10.1001\/jamaneurol.2016.6117\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1001\/jamaneurol.2016.6117<\/a>. <\/li>\n\n\n\n<li>McKhann GM, Knopman DS, Chertkow H, et al.: The diagnosis of dementia due to Alzheimer\u2019s disease: recommendations from the National Institute on Aging-Alzheimer\u2019s Association workgroups on diagnostic guidelines for Alzheimer\u2019s disease. Alzheimers Dement 2011; 7(3): 263\u2013269. <a href=\"https:\/\/doi.org\/10.1016\/j.jalz.2011.03.005\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1016\/j.jalz.2011.03.005<\/a>. <\/li>\n\n\n\n<li>Palmqvist S, Janelidze S, Quiroz YT, et al.: Discriminative Accuracy of Plasma Phospho-tau217 for Alzheimer Disease vs Other Neurodegenerative Disorders. JAMA 2020; 324(8): 772\u2013781. <a href=\"https:\/\/doi.org\/10.1001\/jama.2020.12134\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1001\/jama.2020.12134<\/a>. <\/li>\n\n\n\n<li>Palmqvist S, Tideman P, Cullen N, et al.: Prediction of future Alzheimer\u2019s disease dementia using plasma phospho-tau combined with other accessible measures. Nat Med 2021; 27(6): 1034\u20131042. <a href=\"https:\/\/doi.org\/10.1038\/s41591-021-01348-z\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1038\/s41591-021-01348-z<\/a>. <\/li>\n\n\n\n<li>Palmqvist S, Tideman P, Mattsson-Carlgren N, et al.: Blood Biomarkers to Detect Alzheimer Disease in Primary Care and Secondary Care. JAMA 2024. <a href=\"https:\/\/doi.org\/10.1001\/jama.2024.13855\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1001\/jama.2024.13855<\/a>. <\/li>\n\n\n\n<li>Patel KJ, Yang D, Best JR, et al.: Clinical value of Alzheimer\u2019s disease biomarker testing. Alzheimers Dement 2024 (N Y): 10(2), e12464. <a href=\"https:\/\/doi.org\/10.1002\/trc2.12464\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1002\/trc2.12464<\/a>. <\/li>\n\n\n\n<li>Peters ME, Schwartz S, Han D, et al.: Neuropsychiatric symptoms as predictors of progression to severe Alzheimer\u2019s dementia and death:<br>the Cache County Dementia Progression Study. Am J Psychiatry<br>2015; 172(5): 460\u2013465. <a href=\"https:\/\/doi.org\/10.1176\/appi.ajp.2014.14040480\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1176\/appi.ajp.2014.14040480<\/a>.  <\/li>\n\n\n\n<li>Popp J, Arlt S: Pharmacological treatment of dementia and mild cognitive impairment due to Alzheimer\u2019s disease. Curr Opin Psychiatry 2011; 24(6): 556\u2013561. <a href=\"https:\/\/doi.org\/10.1097\/YCO.0b013e32834b7b96\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1097\/YCO.0b013e32834b7b96<\/a>.  <\/li>\n\n\n\n<li>Popp J, Georgescu D, B\u00fcrge M, et al.: [Biomarkers for the diagnosis of cognitive impairment &#8211; Recommendations from the Swiss Memory Clinics]. Rev Med Suisse 2022; 18(808): 2400\u20132405. <a href=\"https:\/\/doi.org\/10.53738\/REVMED.2022.18.808.2400\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.53738\/REVMED.2022.18.808.2400<\/a>.  <\/li>\n\n\n\n<li>Popp J, Riad M, Freymann K, Jessen F: [Diagnostic lumbar puncture performed in the outpatient setting of a memory clinic. Frequency and risk factors of post-lumbar puncture headache]. Nervenarzt 2007; 78(5): 547\u2013551. <a href=\"https:\/\/doi.org\/10.1007\/s00115-006-2174-z\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1007\/s00115-006-2174-z<\/a>.  <\/li>\n\n\n\n<li>Rabl M, Clark C, Dayon L, et al.: Blood plasma protein profiles of neuropsychiatric symptoms and related cognitive decline in older people. J Neurochem 2023; 164(2): 242\u2013254. <a href=\"https:\/\/doi.org\/10.1111\/jnc.15715\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1111\/jnc.15715<\/a>. <\/li>\n\n\n\n<li>Rabl M, Clark C, Dayon L, et al.: Neuropsychiatric symptoms in cognitive decline and Alzheimer\u2019s disease: biomarker discovery using plasma proteomics. J Neurol Neurosurg Psychiatry 2024. <a href=\"https:\/\/doi.org\/10.1136\/jnnp-2024-333819\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1136\/jnnp-2024-333819<\/a>. <\/li>\n\n\n\n<li>Rabl M, Zullo L, Lewczuk P, et al.: Plasma neurofilament light, glial fibrillary acid protein, and phosphorylated tau 181 as biomarkers for neuropsychiatric symptoms and related clinical disease progression. Alzheimers Res Ther 2024; 16(1): 165. <a href=\"https:\/\/doi.org\/10.1186\/s13195-024-01526-4\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1186\/s13195-024-01526-4<\/a>. <\/li>\n\n\n\n<li>Scheltens P, De Strooper B, Kivipelto M, et al.: Alzheimer\u2019s disease. Lancet 2021; 397(10284): 1577\u20131590. <a href=\"https:\/\/doi.org\/10.1016\/S0140-6736(20)32205-4\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1016\/S0140-6736(20)32205-4<\/a>. <\/li>\n\n\n\n<li>Sheikh F, Ismail Z, Mortby ME, et al.: Prevalence of mild behavioral impairment in mild cognitive impairment and subjective cognitive decline, and its association with caregiver burden. Int Psychogeriatr 2018; 30(2): 233\u2013244.<br><a href=\"https:\/\/doi.org\/10.1017\/s104161021700151x\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1017\/s104161021700151x<\/a>. <\/li>\n\n\n\n<li>Swiss Academy of Medical Sciences (SAMS): Patient\u2019s rights on self-determination (2005). Retrieved 28.09.2024 from <a href=\"http:\/\/www.sams.ch\/dam\/jcr:f3a09643-1766-4e21-9d5b-8da8878b69ae\/grund%20saetze_samw_recht_patientinnen_selbstbestimmung_2005.pdf\" target=\"_blank\" rel=\"noopener\">www.sams.ch\/dam\/jcr:f3a09643-1766-4e21-9d5b-8da8878b69ae\/grund<br>saetze_samw_recht_patientinnen_selbstbestimmung_2005.pdf<\/a> <\/li>\n\n\n\n<li>Thijssen EH, La Joie R, Strom A, et al.: Plasma phosphorylated tau 217 and phosphorylated tau 181 as biomarkers in Alzheimer\u2019s disease and frontotemporal lobar degeneration: a retrospective diagnostic performance study. Lancet Neurol 2021; 20(9): 739\u2013752. <a href=\"https:\/\/doi.org\/10.1016\/S1474-4422(21)00214-3\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1016\/S1474-4422(21)00214-3<\/a>. <\/li>\n\n\n\n<li>WHO. ICD-10: international statistical classification of diseases and related health problems. In (10<sup>th<\/sup> revision, 2<sup>nd<\/sup> ed. ed.). Geneva: World Health Organization 2004. <\/li>\n\n\n\n<li>Wynn MJ, Carpenter BD: Discourse Features Among Providers, Patients, and Companions and Their Effect on Outcomes of Dementia Diagnosis Disclosure. J Gerontol B Psychol Sci Soc Sci 2019; 74(5): 756\u2013763. <a href=\"https:\/\/doi.org\/10.1093\/geronb\/gbx154\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1093\/geronb\/gbx154<\/a>.  <\/li>\n\n\n\n<li>Zetterberg H, Tullh\u00f6g K, Hansson O, et al.: Low incidence of post-lumbar puncture headache in 1,089 consecutive memory clinic patients. Eur Neurol 2010; 63(6): 326\u2013330. <a href=\"https:\/\/doi.org\/10.1159\/000311703\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1159\/000311703<\/a>. <\/li>\n\n\n\n<li>Zou Y, Wang Y, Ma X, et al.: CSF and blood glial fibrillary acidic protein for the diagnosis of Alzheimer\u2019s disease: A systematic review and meta-analysis. Ageing Res Rev 2024; 101: 102485. <a href=\"https:\/\/doi.org\/10.1016\/j.arr.2024.102485\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1016\/j.arr.2024.102485<\/a>.<\/li>\n<\/ol>\n\n\n\n<p><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/10\/sponsorkasten_lilly.png\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1057\" height=\"437\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/10\/sponsorkasten_lilly.png\" alt=\"\" class=\"wp-image-388245\" style=\"width:400px\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/10\/sponsorkasten_lilly.png 1057w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/10\/sponsorkasten_lilly-800x331.png 800w\" sizes=\"(max-width: 1057px) 100vw, 1057px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p><\/p>\n\n\n\n<p class=\"has-small-font-size\"><em>HAUSARZT PRAXIS 2024; 19(11): 4\u201310<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apesar da frequ\u00eancia e da import\u00e2ncia da doen\u00e7a de Alzheimer, em muitos casos esta n\u00e3o \u00e9 diagnosticada ou s\u00f3 \u00e9 diagnosticada numa fase avan\u00e7ada da doen\u00e7a, o que limita consideravelmente&hellip;<\/p>\n","protected":false},"author":7,"featured_media":390393,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Alzheimer","footnotes":""},"category":[11551,22618,11697,11374,11481],"tags":[12159,32299,12163],"powerkit_post_featured":[],"class_list":["post-390381","post","type-post","status-publish","format-standard","has-post-thumbnail","category-rx-pt","category-formacao-cme","category-formacao-com-parceiro","category-neurologia-pt-pt","category-psiquiatria-e-psicoterapia","tag-demencia-pt-pt","tag-doenca-de-alzheimer","tag-problemas-cognitivos-pt-pt","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:31:11","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"pt_PT","wpml_translations":{"es_ES":{"locale":"es_ES","id":390382,"slug":"actualizacion-sobre-el-diagnostico-del-alzheimer-atencion-a-los-biomarcadores-basados-en-el-liquido-cefalorraquideo-y-la-sangre-2","post_title":"Actualizaci\u00f3n sobre el diagn\u00f3stico del Alzheimer: atenci\u00f3n a los biomarcadores basados en el l\u00edquido cefalorraqu\u00eddeo y la sangre","href":"https:\/\/medizinonline.com\/es\/actualizacion-sobre-el-diagnostico-del-alzheimer-atencion-a-los-biomarcadores-basados-en-el-liquido-cefalorraquideo-y-la-sangre-2\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/390381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=390381"}],"version-history":[{"count":3,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/390381\/revisions"}],"predecessor-version":[{"id":390479,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/390381\/revisions\/390479"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media\/390393"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=390381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category?post=390381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=390381"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/powerkit_post_featured?post=390381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}