{"id":449775,"date":"2026-01-05T00:03:00","date_gmt":"2026-01-04T23:03:00","guid":{"rendered":"https:\/\/medizinonline.com\/como-pode-melhorar-o-perfil-de-risco-beneficio\/"},"modified":"2026-01-04T22:44:29","modified_gmt":"2026-01-04T21:44:29","slug":"como-pode-melhorar-o-perfil-de-risco-beneficio","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/pt-pt\/como-pode-melhorar-o-perfil-de-risco-beneficio\/","title":{"rendered":"Como pode melhorar o perfil de risco-benef\u00edcio?"},"content":{"rendered":"\n<p><strong>A pancreatite aguda \u00e9 uma complica\u00e7\u00e3o potencialmente fatal em doentes com s\u00edndrome de quilomicronaemia familiar. Com o olezarsen e o plozasiran, foram desenvolvidos dois candidatos a medicamentos inovadores para os quais est\u00e3o atualmente dispon\u00edveis dados promissores de Fase III. No que diz respeito aos doentes com pancreatite cr\u00f3nica e dor abdominal, est\u00e3o dispon\u00edveis dados interessantes a longo prazo de um estudo de coorte em que a cirurgia imediata foi comparada com a endoscopia como terapia de primeira linha.  <\/strong><\/p>\n\n<div class=\"pmpro\"><div class=\"pmpro_card pmpro_content_message\"><div class=\"pmpro_card_content\">Dieser Inhalt ist nur f\u00fcr Benutzer der Gruppe: Medizinische Fachperson zug\u00e4nglich <br \/><a href=\"https:\/\/medizinonline.com\/pt-pt\/a-minha-conta\/pacotes\/\">Jetzt beitreten<\/a><\/div><div class=\"pmpro_card_actions pmpro_font-medium\">Already a member? <a href=\"https:\/\/medizinonline.com\/pt-pt\/iniciar-sessao\/?redirect_to=https%3A%2F%2Fmedizinonline.com%2Fpt-pt%2Fcomo-pode-melhorar-o-perfil-de-risco-beneficio%2F\">Log in here<\/a><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>A pancreatite aguda \u00e9 uma complica\u00e7\u00e3o potencialmente fatal em doentes com s\u00edndrome de quilomicronaemia familiar. Com o olezarsen e o plozasiran, foram desenvolvidos dois candidatos a medicamentos inovadores para os&#8230;&hellip;... <\/p>\n<div class=\"pmpro\"><div class=\"pmpro_card pmpro_content_message\"><div class=\"pmpro_card_content\">Dieser Inhalt ist nur f\u00fcr Benutzer der Gruppe: Medizinische Fachperson zug\u00e4nglich <br \/><a href=\"https:\/\/medizinonline.com\/pt-pt\/a-minha-conta\/pacotes\/\">Jetzt beitreten<\/a><\/div><div class=\"pmpro_card_actions pmpro_font-medium\">Already a member? <a href=\"https:\/\/medizinonline.com\/pt-pt\/iniciar-sessao\/?redirect_to=https%3A%2F%2Fmedizinonline.com%2Fpt-pt%2Fcomo-pode-melhorar-o-perfil-de-risco-beneficio%2F\">Log in here<\/a><\/div><\/div><\/div>","protected":false},"author":7,"featured_media":449781,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Tratamento da pancreatite: dados de estudos actuais","footnotes":""},"category":[11521,11407,11305,11529,11551],"tags":[86923,86918,14569,86919,68014,29908,86924,86917,86922],"powerkit_post_featured":[],"class_list":["post-449775","post","type-post","status-publish","format-standard","has-post-thumbnail","category-estudos","category-gastroenterologia-e-hepatologia","category-medicina-interna-geral","category-relatorios-do-congresso","category-rx-pt","tag-dados-do-estudo-atual","tag-olezarsen","tag-pancreatite-pt-pt","tag-pancreatite-aguda","tag-pancreatite-cronica-pt-pt","tag-perfil-de-risco-beneficio","tag-plozasiran","tag-quilomicronaemia","tag-sindrome-de-quilomicronaemia","pmpro-level-required","pmpro-level-1","pmpro-no-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 22:25:41","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"pt_PT","wpml_translations":{"es_ES":{"locale":"es_ES","id":449769,"slug":"como-puede-mejorarse-el-perfil-riesgo-beneficio","post_title":"\u00bfC\u00f3mo puede mejorarse el perfil riesgo-beneficio?","href":"https:\/\/medizinonline.com\/es\/como-puede-mejorarse-el-perfil-riesgo-beneficio\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/449775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=449775"}],"version-history":[{"count":1,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/449775\/revisions"}],"predecessor-version":[{"id":449783,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/449775\/revisions\/449783"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media\/449781"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=449775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category?post=449775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=449775"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/powerkit_post_featured?post=449775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}