{"id":549440,"date":"2026-03-25T21:35:31","date_gmt":"2026-03-25T20:35:31","guid":{"rendered":"https:\/\/medizinonline.com\/?p=549440"},"modified":"2026-03-25T21:36:11","modified_gmt":"2026-03-25T20:36:11","slug":"as-intervencoes-no-estilo-de-vida-sao-mais-bem-aceites-com-a-ia","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/pt-pt\/as-intervencoes-no-estilo-de-vida-sao-mais-bem-aceites-com-a-ia\/","title":{"rendered":"As interven\u00e7\u00f5es no estilo de vida s\u00e3o mais bem aceites com a IA"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>O Programa de Preven\u00e7\u00e3o da Diabetes (PPD) continua a ser a norma de ouro quando se trata de prevenir a progress\u00e3o da pr\u00e9-diabetes para a diabetes tipo 2. No entanto, a ades\u00e3o efectiva ao programa continua a ser inaceitavelmente baixa, apesar da sua efic\u00e1cia comprovada. Investigadores americanos investigaram se um programa DPP totalmente automatizado baseado na intelig\u00eancia artificial (IA) poderia produzir resultados compar\u00e1veis aos de um programa tradicional conduzido por humanos.  <\/strong><\/p>\n\n<div class=\"pmpro\"><div class=\"pmpro_card pmpro_content_message\"><div class=\"pmpro_card_content\">Dieser Inhalt ist nur f\u00fcr Benutzer der Gruppe: Medizinische Fachperson zug\u00e4nglich <br \/><a href=\"https:\/\/medizinonline.com\/pt-pt\/a-minha-conta\/pacotes\/\">Jetzt beitreten<\/a><\/div><div class=\"pmpro_card_actions pmpro_font-medium\">Already a member? <a href=\"https:\/\/medizinonline.com\/pt-pt\/iniciar-sessao\/?redirect_to=https%3A%2F%2Fmedizinonline.com%2Fpt-pt%2Fas-intervencoes-no-estilo-de-vida-sao-mais-bem-aceites-com-a-ia%2F\">Log in here<\/a><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>O Programa de Preven\u00e7\u00e3o da Diabetes (PPD) continua a ser a norma de ouro quando se trata de prevenir a progress\u00e3o da pr\u00e9-diabetes para a diabetes tipo 2. No entanto,&#8230;&hellip;... <\/p>\n<div class=\"pmpro\"><div class=\"pmpro_card pmpro_content_message\"><div class=\"pmpro_card_content\">Dieser Inhalt ist nur f\u00fcr Benutzer der Gruppe: Medizinische Fachperson zug\u00e4nglich <br \/><a href=\"https:\/\/medizinonline.com\/pt-pt\/a-minha-conta\/pacotes\/\">Jetzt beitreten<\/a><\/div><div class=\"pmpro_card_actions pmpro_font-medium\">Already a member? <a href=\"https:\/\/medizinonline.com\/pt-pt\/iniciar-sessao\/?redirect_to=https%3A%2F%2Fmedizinonline.com%2Fpt-pt%2Fas-intervencoes-no-estilo-de-vida-sao-mais-bem-aceites-com-a-ia%2F\">Log in here<\/a><\/div><\/div><\/div>","protected":false},"author":7,"featured_media":549441,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Intelig\u00eancia artificial na preven\u00e7\u00e3o da diabetes","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11551,11397,11521,11524,11305,11474],"tags":[12023,88492,14153,88493,51194,88491,88490,88494],"powerkit_post_featured":[],"class_list":["post-549440","post","type-post","status-publish","format-standard","has-post-thumbnail","category-rx-pt","category-endocrinologia-e-diabetologia-2","category-estudos","category-formacao-continua","category-medicina-interna-geral","category-prevencao-e-cuidados-de-saude","tag-diabetes-tipo-2-pt-pt","tag-dpp","tag-inteligencia-artificial","tag-intervencoes-no-estilo-de-vida-2","tag-ki-pt-pt","tag-pre-diabetes","tag-prevencao-da-diabetes","tag-programa-de-prevencao-da-diabetes","pmpro-level-required","pmpro-level-1","pmpro-no-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 17:47:59","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"pt_PT","wpml_translations":{"es_ES":{"locale":"es_ES","id":549445,"slug":"las-intervenciones-sobre-el-estilo-de-vida-se-aceptan-mejor-con-la-ia","post_title":"Las intervenciones sobre el estilo de vida se aceptan mejor con la IA","href":"https:\/\/medizinonline.com\/es\/las-intervenciones-sobre-el-estilo-de-vida-se-aceptan-mejor-con-la-ia\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/549440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=549440"}],"version-history":[{"count":1,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/549440\/revisions"}],"predecessor-version":[{"id":549442,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/549440\/revisions\/549442"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media\/549441"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=549440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category?post=549440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=549440"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/powerkit_post_featured?post=549440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}