{"id":554943,"date":"2026-04-18T02:00:00","date_gmt":"2026-04-18T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/ingredientes-activos-modernos-e-estilo-de-vida-cada-passo-conta\/"},"modified":"2026-04-22T16:06:00","modified_gmt":"2026-04-22T14:06:00","slug":"ingredientes-activos-modernos-e-estilo-de-vida-cada-passo-conta","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/pt-pt\/ingredientes-activos-modernos-e-estilo-de-vida-cada-passo-conta\/","title":{"rendered":"Ingredientes activos modernos e estilo de vida &#8211; cada passo conta"},"content":{"rendered":"\n<p><strong>Embora os diab\u00e9ticos tenham um risco acrescido de desenvolver doen\u00e7as cardiovasculares, como enfarte do mioc\u00e1rdio, insufici\u00eancia card\u00edaca ou acidente vascular cerebral, os dados cient\u00edficos sugerem que \u00e9 poss\u00edvel obter efeitos protectores atrav\u00e9s do melhor controlo glic\u00e9mico poss\u00edvel e da utiliza\u00e7\u00e3o atempada de inibidores do SGLT2 e agonistas dos receptores GLP-1. Os efeitos preventivos do exerc\u00edcio f\u00edsico tamb\u00e9m n\u00e3o devem ser subestimados &#8211; o que, obviamente, n\u00e3o se aplica apenas \u00e0 diabetes manifesta &#8211; o objetivo deve ser pelo menos 150 minutos de atividade moderada por semana, idealmente complementados por treino de for\u00e7a de intensidade moderada. Foram recentemente publicadas v\u00e1rias meta-an\u00e1lises e recomenda\u00e7\u00f5es de consenso a este respeito.    <\/strong><\/p>\n\n<div class=\"pmpro\"><div class=\"pmpro_card pmpro_content_message\"><div class=\"pmpro_card_content\">Dieser Inhalt ist nur f\u00fcr Benutzer der Gruppe: Medizinische Fachperson zug\u00e4nglich <br \/><a href=\"https:\/\/medizinonline.com\/pt-pt\/a-minha-conta\/pacotes\/\">Jetzt beitreten<\/a><\/div><div class=\"pmpro_card_actions pmpro_font-medium\">Already a member? <a href=\"https:\/\/medizinonline.com\/pt-pt\/iniciar-sessao\/?redirect_to=https%3A%2F%2Fmedizinonline.com%2Fpt-pt%2Fingredientes-activos-modernos-e-estilo-de-vida-cada-passo-conta%2F\">Log in here<\/a><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Embora os diab\u00e9ticos tenham um risco acrescido de desenvolver doen\u00e7as cardiovasculares, como enfarte do mioc\u00e1rdio, insufici\u00eancia card\u00edaca ou acidente vascular cerebral, os dados cient\u00edficos sugerem que \u00e9 poss\u00edvel obter efeitos&#8230;&hellip;... <\/p>\n<div class=\"pmpro\"><div class=\"pmpro_card pmpro_content_message\"><div class=\"pmpro_card_content\">Dieser Inhalt ist nur f\u00fcr Benutzer der Gruppe: Medizinische Fachperson zug\u00e4nglich <br \/><a href=\"https:\/\/medizinonline.com\/pt-pt\/a-minha-conta\/pacotes\/\">Jetzt beitreten<\/a><\/div><div class=\"pmpro_card_actions pmpro_font-medium\">Already a member? <a href=\"https:\/\/medizinonline.com\/pt-pt\/iniciar-sessao\/?redirect_to=https%3A%2F%2Fmedizinonline.com%2Fpt-pt%2Fingredientes-activos-modernos-e-estilo-de-vida-cada-passo-conta%2F\">Log in here<\/a><\/div><\/div><\/div>","protected":false},"author":7,"featured_media":554945,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Diabetes tipo 2: a redu\u00e7\u00e3o do risco cardiovascular \u00e9 realista  ","footnotes":""},"category":[11367,11397,11521,11474,11529,11551],"tags":[23813,12023,65626,23574,91449],"powerkit_post_featured":[],"class_list":["post-554943","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cardiologia-pt-pt","category-endocrinologia-e-diabetologia-2","category-estudos","category-prevencao-e-cuidados-de-saude","category-relatorios-do-congresso","category-rx-pt","tag-agonistas-receptores-de-glp-1","tag-diabetes-tipo-2-pt-pt","tag-glp-1-ra-pt-pt","tag-inibidores-sglt2","tag-reducao-do-risco-cardiovascular","pmpro-level-required","pmpro-level-1","pmpro-no-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 13:46:28","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"pt_PT","wpml_translations":{"es_ES":{"locale":"es_ES","id":554967,"slug":"modernos-principios-activos-y-estilo-de-vida-cada-paso-cuenta","post_title":"Modernos principios activos y estilo de vida: cada paso cuenta","href":"https:\/\/medizinonline.com\/es\/modernos-principios-activos-y-estilo-de-vida-cada-paso-cuenta\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/554943","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=554943"}],"version-history":[{"count":1,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/554943\/revisions"}],"predecessor-version":[{"id":554946,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/554943\/revisions\/554946"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media\/554945"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=554943"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category?post=554943"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=554943"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/powerkit_post_featured?post=554943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}