{"id":558478,"date":"2026-06-12T23:00:00","date_gmt":"2026-06-12T21:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/alivio-da-dor-dos-sintomas-e-melhoria-da-capacidade-funcional-tanto-no-tratamento-agudo-como-na-prevencao\/"},"modified":"2026-06-17T10:01:58","modified_gmt":"2026-06-17T08:01:58","slug":"alivio-da-dor-dos-sintomas-e-melhoria-da-capacidade-funcional-tanto-no-tratamento-agudo-como-na-prevencao","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/pt-pt\/alivio-da-dor-dos-sintomas-e-melhoria-da-capacidade-funcional-tanto-no-tratamento-agudo-como-na-prevencao\/","title":{"rendered":"Al\u00edvio da dor, dos sintomas e melhoria da capacidade funcional \u2013 tanto no tratamento agudo como na preven\u00e7\u00e3o"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>A gest\u00e3o da enxaqueca vai al\u00e9m do controlo dos sintomas agudos e pode incluir estrat\u00e9gias preventivas em doentes com uma carga de doen\u00e7a significativa. Embora os triptanos continuem a ser a terapia de primeira linha recomendada para a enxaqueca aguda, mais de 30 % dos doentes n\u00e3o podem utiliz\u00e1-los ou n\u00e3o obt\u00eam al\u00edvio suficiente. Os antagonistas dos recetores do pept\u00eddeo relacionado com o gene da calcitonina (CGRP) revelaram-se, por isso, uma op\u00e7\u00e3o terap\u00eautica alternativa promissora.  <\/strong><\/p>\n\n<div class=\"pmpro\"><div class=\"pmpro_card pmpro_content_message\"><div class=\"pmpro_card_content\">Dieser Inhalt ist nur f\u00fcr Benutzer der Gruppe: Medizinische Fachperson zug\u00e4nglich <br \/><a href=\"https:\/\/medizinonline.com\/pt-pt\/a-minha-conta\/pacotes\/\">Jetzt beitreten<\/a><\/div><div class=\"pmpro_card_actions pmpro_font-medium\">Already a member? <a href=\"https:\/\/medizinonline.com\/pt-pt\/iniciar-sessao\/?redirect_to=https%3A%2F%2Fmedizinonline.com%2Fpt-pt%2Falivio-da-dor-dos-sintomas-e-melhoria-da-capacidade-funcional-tanto-no-tratamento-agudo-como-na-prevencao%2F\">Log in here<\/a><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>A gest\u00e3o da enxaqueca vai al\u00e9m do controlo dos sintomas agudos e pode incluir estrat\u00e9gias preventivas em doentes com uma carga de doen\u00e7a significativa. Embora os triptanos continuem a ser&#8230;&hellip;... <\/p>\n<div class=\"pmpro\"><div class=\"pmpro_card pmpro_content_message\"><div class=\"pmpro_card_content\">Dieser Inhalt ist nur f\u00fcr Benutzer der Gruppe: Medizinische Fachperson zug\u00e4nglich <br \/><a href=\"https:\/\/medizinonline.com\/pt-pt\/a-minha-conta\/pacotes\/\">Jetzt beitreten<\/a><\/div><div class=\"pmpro_card_actions pmpro_font-medium\">Already a member? <a href=\"https:\/\/medizinonline.com\/pt-pt\/iniciar-sessao\/?redirect_to=https%3A%2F%2Fmedizinonline.com%2Fpt-pt%2Falivio-da-dor-dos-sintomas-e-melhoria-da-capacidade-funcional-tanto-no-tratamento-agudo-como-na-prevencao%2F\">Log in here<\/a><\/div><\/div><\/div>","protected":false},"author":7,"featured_media":558479,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Gepante na enxaqueca","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11551,11453,11524,11305,11374],"tags":[94390,81155,13909,22113,94391,94392,16159],"powerkit_post_featured":[],"class_list":["post-558478","post","type-post","status-publish","format-standard","has-post-thumbnail","category-rx-pt","category-farmacologia-e-toxicologia","category-formacao-continua","category-medicina-interna-geral","category-neurologia-pt-pt","tag-cgrp-ra","tag-chita","tag-enxaqueca","tag-fisiopatologia-pt-pt","tag-prevencao-das-enxaquecas","tag-rimegepant","tag-triptanos","pmpro-level-required","pmpro-level-1","pmpro-no-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 09:59:04","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"pt_PT","wpml_translations":{"es_ES":{"locale":"es_ES","id":558492,"slug":"alivio-del-dolor-los-sintomas-y-mejora-de-la-capacidad-funcional-tanto-en-casos-agudos-como-a-titulo-preventivo","post_title":"Alivio del dolor, los s\u00edntomas y mejora de la capacidad funcional, tanto en casos agudos como a t\u00edtulo preventivo","href":"https:\/\/medizinonline.com\/es\/alivio-del-dolor-los-sintomas-y-mejora-de-la-capacidad-funcional-tanto-en-casos-agudos-como-a-titulo-preventivo\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/558478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=558478"}],"version-history":[{"count":1,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/558478\/revisions"}],"predecessor-version":[{"id":558480,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/558478\/revisions\/558480"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media\/558479"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=558478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category?post=558478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=558478"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/powerkit_post_featured?post=558478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}