{"id":59181,"count":1,"description":"","link":"https:\/\/medizinonline.com\/pt-pt\/tag\/lichenoid-pt-pt\/","name":"lichenoid","slug":"lichenoid-pt-pt","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags\/59181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts?tags=59181"},{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/article_rx?tags=59181"},{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/post_dl?tags=59181"},{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tribe_events?tags=59181"},{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tec_calendar_embed?tags=59181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}